{"id":341391,"date":"2015-12-10T21:38:49","date_gmt":"2015-12-11T03:38:49","guid":{"rendered":"http:\/\/futboltotal.com.mx\/?p=341391"},"modified":"2015-12-10T21:50:40","modified_gmt":"2015-12-11T03:50:40","slug":"polemico-penal-en-la-final-del-apertura-2015","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/videos\/polemico-penal-en-la-final-del-apertura-2015\/2015\/12","title":{"rendered":"Pol\u00e9mico penal en la Final del Apertura 2015"},"content":{"rendered":"<p>La pol\u00e9mica se hizo presente en la <strong>Final<\/strong> del <strong>Apertura 2015<\/strong>. El \u00e1rbitro central, Jos\u00e9 Alfredo Pe\u00f1aloza, decret\u00f3 un penal de Javier Cortes, jugador de <strong>Pumas<\/strong>, sobre Rafael Sobis, elemento de los <strong>Tigres<\/strong>. Acci\u00f3n apretada dentro del \u00e1rea.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/vine.co\/v\/iZOPrziH7aM\/embed\/simple\" frameborder=\"0\"><\/iframe><\/p>\n<p><script src=\"https:\/\/platform.vine.co\/static\/scripts\/embed.js\"><\/script>Tras la acci\u00f3n, las reacciones no se hicieron esperar. Una de ellas, la del ex silbante mexicano Marco Antonio Rodr\u00edguez, quien consider\u00f3 que la jugada no debi\u00f3 ser marcada como penal. <\/p>\n<blockquote class=\"twitter-tweet\" lang=\"es\"><p>Contacto NO PENAL \u2014 Marco A. Rodr\u00edguez (@ChiquimarcoMx) <a href=\"https:\/\/twitter.com\/ChiquimarcoMx\/status\/675152598735962113\">diciembre 11, 2015<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p><em>Chiquimarco<\/em> consider\u00f3 que Jos\u00e9 Alfredo Pe\u00f1aloza, quien en la temporada regular del <strong>Apertura 2015<\/strong> marc\u00f3 dos penales dudosos contra\u00a0<strong>Pumas<\/strong> en su duelo ante\u00a0Cruz Azul -jornada 9-, observ\u00f3 err\u00f3neamente una carga sobre su adversario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pe\u00f1aloza sanciona apretada falta de Cort\u00e9s sobre Sobis<\/p>\n","protected":false},"author":20,"featured_media":341396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2198,3845,4],"tags":[1752,74,5973],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/341391"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=341391"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/341391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/341396"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=341391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=341391"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=341391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}