{"id":383262,"date":"2016-03-25T13:14:10","date_gmt":"2016-03-25T19:14:10","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=383262"},"modified":"2016-03-25T13:14:10","modified_gmt":"2016-03-25T19:14:10","slug":"liga-mx-brilla-en-eliminatorias-conmebol","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/destacado-home\/liga-mx-brilla-en-eliminatorias-conmebol\/2016\/03","title":{"rendered":"Liga MX \u201cbrilla\u201d en Eliminatorias de Conmebol"},"content":{"rendered":"<p>Con 47 elementos, la <strong><a href=\"http:\/\/www.futboltotal.com.mx\/futbol-mexicano\/\" target=\"_blank\">Liga MX<\/a><\/strong> tuvo presencia en las Eliminatorias de la <strong>Conmebol<\/strong>, donde se disfrutaron duelos llenos de pasi\u00f3n y alegr\u00eda; gracias a la decena de jugadores que militan en el futbol mexicano no es de extra\u00f1arse que algunos lograron brillar.<\/p>\n<p>El caso con mayor relevancia fue de lejos el de Edwin Cardona (Monterrey) que ingres\u00f3 al minuto 62\u2019 y se convirti\u00f3 en el h\u00e9roe de Colombia al marcar el gol (92\u2019) del triunfo 3-2 frente a Bolivia, mientras que los defensas del Pachuca, \u00d3scar Murillo y Stefan Medina, estuvieron todo el partido.<\/p>\n<p><a href=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-2.jpg\" rel=\"attachment wp-att-383265\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-383265\" src=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-2.jpg\" alt=\"liga-mx-conmebol-fecha-fifa-noticias-2\" srcset=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-2.jpg 820w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-2-300x128.jpg 300w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-2-768x328.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/a><\/p>\n<p>Los que sufrieron con la escuadra <em>cafetera<\/em> fueron Dayro Moreno (Xolos) y Luis Qui\u00f1ones (Pumas), porque se quedaron en la banca. Cabe recordar que el atacante de la UNAM est\u00e1 en la mira por sus indisciplinas con su ex equipo Santa Fe, por eso su convocatoria caus\u00f3 pol\u00e9mica.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/futbol-mexicano\/\" target=\"_blank\">LEER M\u00c1S: Toda la informaci\u00f3n de la Liga MX<\/a><\/strong><\/span><\/p>\n<p>En el duelo entre Ecuador y Paraguay (2-2), la <strong>Liga MX<\/strong> aporta m\u00e1s elementos con nueve, en el caso de la <em>Tricolor<\/em> Fidel Mart\u00ednez (Pumas) estuvo 78\u2019 minutos, tiempo en el cual se encarg\u00f3 de generar juego ofensivo por las bandas. Pero el que mayor relevancia tuvo fue Walter Ayov\u00ed, capit\u00e1n de la selecci\u00f3n. Finalmente, Michael Arroyo (45\u2019) estuvo medio tiempo aunque no pudo hacerse presente en el marcador.<\/p>\n<p>Por el lado guaran\u00ed, Miguel Samudio (Am\u00e9rica), Paulo da Silva y Richard Ru\u00edz del Toluca; estuvieron los 90 minutos. \u00c9dgar Ben\u00edtez (Quer\u00e9taro) y Jorge Ben\u00edtez (Cruz Azul) no pudieron demostrar su racha goleadora, empero el que no tuvo oportunidad de lucirse fue Osvaldo Mart\u00ednez (Am\u00e9rica) al quedarse en la banca.<\/p>\n<p><a href=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-1.jpg\" rel=\"attachment wp-att-383266\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-383266\" src=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-1.jpg\" alt=\"liga-mx-conmebol-fecha-fifa-noticias-1\" srcset=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-1.jpg 820w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-1-300x128.jpg 300w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/liga-mx-conmebol-fecha-fifa-noticias-1-768x328.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/a><\/p>\n<p>En Chile los jugadores que est\u00e1n en la <strong>Liga MX<\/strong> palidecieron porque ni Bryan Rabello (Santos) y Francisco Silva (Chiapas) pudieron hacer diferencia, aunque el <em>Guerrero<\/em> fue el m\u00e1s preocupante porque salt\u00f3 a la cancha al minuto 20 y sali\u00f3 de cambio al 68\u2019. En tanto, Fernando Meneses (Veracruz) no vio acci\u00f3n, lo mismo que el argentino Nahuel Guzm\u00e1n (Tigres).<\/p>\n<p>Por \u00faltimo, el peruano Christian Cueva estuvo todo el cotejo, pero fue incapaz de ayudar para evitar la igualada 2-2 con Venezuela.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>VIDEO<\/strong>: Agenda de Tv de la Fecha FIFA<\/span><br \/>\n[video_player]https:\/\/player.vimeo.com\/external\/160014525.sd.mp4?s=f36ce07574ef9d81895a39e0efb20e96fec2def5&amp;profile_id=165[\/video_player]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunos jugadores que militan en el futbol mexicano derrocharon calidad <\/p>\n","protected":false},"author":20,"featured_media":383263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,3839,2198,3845],"tags":[1392,64],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/383262"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=383262"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/383262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/383263"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=383262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=383262"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=383262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}