{"id":383460,"date":"2016-03-27T11:29:53","date_gmt":"2016-03-27T17:29:53","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=383460"},"modified":"2016-03-27T11:29:53","modified_gmt":"2016-03-27T17:29:53","slug":"la-selfie-rubens-sambueza","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-mexicano\/la-selfie-rubens-sambueza\/2016\/03","title":{"rendered":"La selfie de Rubens Sambueza"},"content":{"rendered":"<p>En partido amistoso disputado en Houston, Texas, <strong><a href=\"http:\/\/futboltotal.com.mx\/equipos\/tigres\/\" target=\"_blank\">Tigres<\/a><\/strong> se encarg\u00f3 de pulverizar al <strong><a href=\"http:\/\/futboltotal.com.mx\/equipos\/america\/\" target=\"_blank\">Am\u00e9rica<\/a><\/strong> en suelo norteamericano, pero lo m\u00e1s destacado no fue el 3-2 a favor de los felinos, si no la intromisi\u00f3n de varios espont\u00e1neos al campo, donde, uno de ellos se tom\u00f3 una selfie con <strong>Rubens Sambueza<\/strong>.<\/p>\n<p><strong>Tigres<\/strong> ganaba el encuentro por 3-0 hasta el medio tiempo, luego de anotaciones de Fernando Fern\u00e1ndez al 7\u2019, y H\u00e9ctor Mancilla al 18\u2019 y 45\u2019; para el complemento, Oribe Peralta marc\u00f3 el descuento al 63\u2019 y al minuto 73, un autogol de un futbolista juvenil de las UANL, sell\u00f3 el resultado.<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/2016\/03\/tabla-general-la-liga-mx-clausura-2016\/\" target=\"_blank\">LEER M\u00c1S: Clausura 2016, sin pendientes<\/a><\/span><\/strong><\/p>\n<p>Pero en la recta final del encuentro, tres aficionados ingresaron al terreno de juego, y uno de ellos aprovech\u00f3 para tomarse una selfie con <strong>Rubens Sambueza<\/strong>; el futbolista del <strong>Am\u00e9rica<\/strong> accedi\u00f3 a tomarse la fotograf\u00eda, que de inmediato caus\u00f3 sencaci\u00f3n en las redes sociales.<\/p>\n<p><a href=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/03\/rubens-sambueza-selfie.png\" rel=\"attachment wp-att-383463\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-383463 aligncenter\" src=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/03\/rubens-sambueza-selfie.png\" alt=\"rubens-sambueza-selfie\" srcset=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/rubens-sambueza-selfie.png 365w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/03\/rubens-sambueza-selfie-262x300.png 262w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/a><\/p>\n<p><span style=\"color: #ff0000;\">VIDEO: Liga MX versi\u00f3n Superh\u00e9roes de DC C\u00f3mics<\/span><\/p>\n<p>[video_player]https:\/\/player.vimeo.com\/external\/160168822.sd.mp4?s=7e2d0cde2ccd4fdd61b7c84c89d685d24eb1ead7&amp;profile_id=165[\/video_player]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante un partido, un espont\u00e1neo se tom\u00f3 foto con el azulcrema<\/p>\n","protected":false},"author":20,"featured_media":383464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5419,2198,3845,5950],"tags":[5959,5460,64,808,5973],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/383460"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=383460"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/383460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/383464"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=383460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=383460"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=383460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}