{"id":385266,"date":"2016-04-03T19:15:31","date_gmt":"2016-04-04T01:15:31","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=385266"},"modified":"2016-04-03T19:23:27","modified_gmt":"2016-04-04T01:23:27","slug":"lionel-messi-futbol-implicados-en-panama-papers","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-internacional\/lionel-messi-futbol-implicados-en-panama-papers\/2016\/04","title":{"rendered":"Messi y el futbol, implicados en Panam\u00e1 Papers"},"content":{"rendered":"<p>Una enorme filtraci\u00f3n de documentos confidenciales ha revelado c\u00f3mo personas adineradas y poderosas usan los para\u00edsos fiscales para ocultar su riqueza. Los papeles revelados pertenecen a la empresa paname\u00f1a <strong>Mossack Fonseca<\/strong>, y en ellos podr\u00edan estar implicados <strong>Lionel Messi<\/strong> y otros futbolistas.<\/p>\n<p><strong>Mossack Fonseca<\/strong> es una empresa offshore, es decir, que trabaja con las empresas de distintos pa\u00edses, y, tras una investigaci\u00f3n mundial sobre corrupci\u00f3n, se dieron a conocer documentos de la firma, donde se vinculan a 72 jefes de Estado, entre los que se encuentran mexicanos; adem\u00e1s de haber narcotraficantes y hasta futbolistas, el principal de ellos es <strong>Lionel Messi<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/04\/mossack-fonseca-panama-papers.png\" rel=\"attachment wp-att-385269\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-385269\" src=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/04\/mossack-fonseca-panama-papers.png\" alt=\"mossack-fonseca-panama-papers\" srcset=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/mossack-fonseca-panama-papers.png 820w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/mossack-fonseca-panama-papers-300x110.png 300w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/mossack-fonseca-panama-papers-768x281.png 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/2016\/04\/todos-somos-leicester-city-iker-casillas\/\" target=\"_blank\">LEER M\u00c1S: Todos somos Leicester City<\/a><\/strong><\/span><\/p>\n<p>De acuerdo a los <strong>Panam\u00e1 Papers<\/strong>, como se le conoce a los documentos revelados, el padre de <strong>Lionel Messi<\/strong> cre\u00f3 una empresa fantasma en territorio canalero, llamada <em>Mega Star Enterprises<\/em>, con el fin de evadir impuestos.<\/p>\n<p>Adem\u00e1s de <strong>Lionel Messi<\/strong>, Michel Platini, futbolistas de la Real Sociedad, entre muchas otras figuras relacionadas con el futbol, est\u00e1n implicados en los <strong>Panam\u00e1 Papers<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La investigaci\u00f3n mundial sobre fraude fiscal, incluye a jugadores <\/p>\n","protected":false},"author":20,"featured_media":385268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5419,3839],"tags":[6012,6966],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/385266"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=385266"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/385266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/385268"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=385266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=385266"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=385266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}