{"id":385335,"date":"2016-04-03T21:48:58","date_gmt":"2016-04-04T03:48:58","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=385335"},"modified":"2016-04-04T07:23:05","modified_gmt":"2016-04-04T13:23:05","slug":"jorge-vergara-trollea-a-pumas","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/destacado-home\/jorge-vergara-trollea-a-pumas\/2016\/04","title":{"rendered":"Vergara y Chivas trollean a Pumas"},"content":{"rendered":"<p>Tras el contundente triunfo de los <strong><a href=\"http:\/\/www.futboltotal.com.mx\/equipos\/unam\/\" target=\"_blank\">Pumas de la UNAM<\/a><\/strong> sobre las <strong><a href=\"http:\/\/www.futboltotal.com.mx\/equipos\/guadalajara\/\" target=\"_blank\">Chivas del Guadalajara<\/a><\/strong>, el presidente del <em>Reba\u00f1o<\/em>, <strong>Jorge Vergara<\/strong>, no dej\u00f3 escapar la oportunidad de tundir al cuadro <em>felino<\/em>&#8230;<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">\u00a1Es cierto! \u00a1Es cierto! <a href=\"https:\/\/t.co\/PLhUEjuz82\">pic.twitter.com\/PLhUEjuz82<\/a><\/p>\n<p>\u2014 Jorge Vergara M. (@jorgevergara) <a href=\"https:\/\/twitter.com\/jorgevergara\/status\/716828291714297857\">4 de abril de 2016<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p>Adem\u00e1s, <strong>Jorge Vergara<\/strong> destac\u00f3 la actuaci\u00f3n de los j\u00f3venes de las <strong>Chivas<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\"><p>\nUn enorme orgullo ver a nuestros j\u00f3venes como hoy; lo digo como aficionado. Much\u00edsimas gracias y felicidades <a href=\"https:\/\/twitter.com\/Chivas\">@Chivas<\/a> <a href=\"https:\/\/twitter.com\/peladoalmeyda\">@peladoalmeyda<\/a> ? ?\u2764\ufe0f??<\/p>\n<p>\u2014 Jorge Vergara M. (@jorgevergara) <a href=\"https:\/\/twitter.com\/jorgevergara\/status\/716829201949536257\">4 de abril de 2016<\/a>\n<\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p><a href=\"http:\/\/www.futboltotal.com.mx\/2016\/04\/en-vivo-chivas-vs-pumas-jornada-12-liga-mx\/\"><strong>AS\u00cd SE VIVI\u00d3<\/strong> | <strong>Chivas 4-0 Pumas<\/strong> | Revive las acciones m\u00e1s destacadas del partido<\/a><\/p>\n<p>Por su parte, <strong>Chivas<\/strong> tambi\u00e9n dedic\u00f3 una singular publicaci\u00f3n en redes sociales. En el mensaje, cambiaron el &#8216;Hecho en CU&#8217;, leyenda que acompa\u00f1\u00f3 en inicio de la rivalidad del <em>Reba\u00f1o<\/em> de <strong>Jorge Vergara<\/strong> con el cuadro de la UNAM,\u00a0por &#8216;Hecho en M\u00e9xico&#8217;.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">Somos Chivas, 100% mexicanos ?? <a href=\"https:\/\/t.co\/gAO6xuc18B\">pic.twitter.com\/gAO6xuc18B<\/a><\/p>\n<p>\u2014 CHIVAS (@Chivas) <a href=\"https:\/\/twitter.com\/Chivas\/status\/716833587996135424\">4 de abril de 2016<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p>Tambi\u00e9n, el cuadro <em>rojiblanco<\/em> insisti\u00f3 en la hegemon\u00eda de las <strong>Chivas<\/strong> sobre <strong>Pumas<\/strong> en Guadalajara.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\"><p>\n? ? &#8220;Aquel que no conoce su historia est\u00e1 condenado a repetirla&#8221; ? ? <a href=\"https:\/\/twitter.com\/PumasMX\">@PumasMX<\/a> <a href=\"https:\/\/t.co\/Q2D1coCx9T\">pic.twitter.com\/Q2D1coCx9T<\/a><\/p>\n<p>\u2014 CHIVAS (@Chivas) <a href=\"https:\/\/twitter.com\/Chivas\/status\/716828664646619136\">4 de abril de 2016<\/a>\n<\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El due\u00f1o de las Chivas celebr\u00f3 el contundente triunfo del Reba\u00f1o<\/p>\n","protected":false},"author":20,"featured_media":385393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,2198,3845],"tags":[70,243,74],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/385335"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=385335"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/385335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/385393"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=385335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=385335"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=385335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}