{"id":385441,"date":"2016-04-04T12:31:04","date_gmt":"2016-04-04T18:31:04","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=385441"},"modified":"2016-04-04T14:48:03","modified_gmt":"2016-04-04T20:48:03","slug":"mexicanos-salpicados-en-el-panama-papers","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-mexicano\/mexicanos-salpicados-en-el-panama-papers\/2016\/04","title":{"rendered":"Mexicanos salpicados en el Panam\u00e1 Papers"},"content":{"rendered":"<p>Entre los m\u00e1s de 11.5 millones de archivos que fueron filtrados este domingo en el <strong>Panam\u00e1 Papers<\/strong>, que involucran a la firma legal paname\u00f1a Mossack Fonseca con el blanqueo de dinero en para\u00edsos fiscales y sociedades ficticias, <a href=\"http:\/\/www.futboltotal.com.mx\/2016\/04\/lionel-messi-futbol-implicados-en-panama-papers\/\">no solo estar\u00eda implicado el astro argentin Lionel Messi,<\/a> sino tambi\u00e9n algunas personalidades que tuvieron relaci\u00f3n con el futbol mexicano.<\/p>\n<p>De acuerdo con la investigaci\u00f3n realizada por el diario alem\u00e1n <em>Suddeutsche Zeitung<\/em> y el Consorcio Internacional de Periodismo Investigativo (ICIJ), presuntamente estar\u00edan implicados: Amado Ya\u00f1ez, Carlos Hank Rhon, Guillermo Ca\u00f1edo White y Ricardo Salinas Pliego.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/futbol-internacional\/\">LEER M\u00c1S: Todas las noticias de futbol internacional<\/a><\/strong><\/span><\/p>\n<p>Amado Ya\u00f1ez, ex due\u00f1o de la emprea Oceanograf\u00eda, incursion\u00f3 en el futbol mexicano en 2013. Dio un golpe de multipriopiedad al comprar las franquicias de Neza FC, Jaguares de Chiapas y Quer\u00e9taro. Estas dos \u00faltimas fueron un caso especial pues cuando descendi\u00f3 <em>Gallos<\/em>, adquiri\u00f3 a los <em>felinos\u00a0<\/em>e hizo un cambio de sede para as\u00ed regresar a Quer\u00e9taro el fubol de Primera Divisi\u00f3n. Est\u00e1 inmiscuido porque habr\u00eda recurrido a varias corporaciones en las Islas V\u00edrgenes Brit\u00e1nicas para evadir el pago de impuestos.<\/p>\n<p>La familia Hank Rohn tambi\u00e9n figura entre los implicados. Y es que pese a que el actual presidente de los Xolos de Tijuana, Jorgearto Hank Rhon, no est\u00e1 directamente involucruado s\u00ed lo est\u00e1 Carlos Hank Rhon, quien busc\u00f3 los servicios de la empresa Mossack Fonseca, pero recibi\u00f3 una negativa de la misma, toda vez que ten\u00eda &#8220;desprestigi\u00f3&#8221; tras estar involucrada la familia en la Operaci\u00f3n Tigre Blanco, emprendida en 2011 por el gobierno de Estados Unidos, seg\u00fan publica el sitio de <em>Proceso<\/em>.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/2016\/04\/filtra-millonario-contrato-de-memphis-depay\/\">LEER M\u00c1S: Filtran millonario contrato de Memphis Depay<\/a><\/strong><\/span><\/p>\n<p>El expresidente del club Am\u00e9rica, Guillermo Ca\u00f1edo White tambi\u00e9n est\u00e1 en la lista negra. El acaudalado empresario tambi\u00e9n fungi\u00f3 com Vicepresidente de la Concacaf hasta 2011, cuando fue relevado por Justino Compean, mandam\u00e1s de la Federaci\u00f3n Mexicana de Futbol. De acuerdo con la investigaci\u00f3n publicada, habr\u00eda tenido una sociedad con \u00c1ngel Remigio G\u00f3nzalez en una de las empresas de las Islas V\u00edrgenes Brit\u00e1nicas.<\/p>\n<p>El \u00faltimo en la lista es Ricardo Salinas Pliego, quien en mayo del 2015, previo al cl\u00e1sico tapat\u00edo, apost\u00f3 nada menos que 1 mill\u00f3n de pesos con el due\u00f1o de Chivas, Jorge Vergara. Pliego, propietario de Grupo Salinas, es otro \u00edcono de la multipropiedad, pues es due\u00f1o de Monarcas Morelia y Atlas, al que adquiri\u00f3 en 2013. Su v\u00ednculo es con una de las empresas de la Islas V\u00edrgenes, la cual habr\u00eda usado como intermediaria para comprar un lujoso yate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Involucran a personalidades del futbol mexicano en esc\u00e1ndalo de corrupci\u00f3n<\/p>\n","protected":false},"author":20,"featured_media":385448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2198,3845,5950],"tags":[6966],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/385441"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=385441"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/385441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/385448"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=385441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=385441"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=385441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}