{"id":386336,"date":"2016-04-07T13:23:22","date_gmt":"2016-04-07T19:23:22","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=386336"},"modified":"2016-04-07T15:55:28","modified_gmt":"2016-04-07T21:55:28","slug":"los-cuatro-primeros-extranjeros-del-cruz-azul","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-mexicano\/los-cuatro-primeros-extranjeros-del-cruz-azul\/2016\/04","title":{"rendered":"Los primeros extranjeros del Cruz Azul"},"content":{"rendered":"<p>Para la temporada 1971-72, <strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/equipos\/cruz-azul\/\" target=\"_blank\">Cruz Azul<\/a><\/span><\/strong> integr\u00f3 a su plantilla\u00a0a cuatro jugadores extranjeros. Por primera vez en su historia, la <em>M\u00e1quina<\/em> cont\u00f3 con elementos for\u00e1neos.\u00a0Un cuarteto magn\u00edfico, que dej\u00f3 una huella imborrable, tanto para los seguidores\u00a0<em>celestes<\/em> como para toda afici\u00f3n mexicana<\/p>\n<div id=\"gallery2wM\" style=\"display:none;\"><img alt=\"\" src=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-marin.jpg\" data-image=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-marin.jpg\" data-description=\"extranjeros-cruz-azul-marin\"><img alt=\"\" src=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-quintano.jpg\" data-image=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-quintano.jpg\" data-description=\"extranjeros-cruz-azul-quintano\"><img alt=\"\" src=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-alberto-gomez.jpg\" data-image=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-alberto-gomez.jpg\" data-description=\"extranjeros-cruz-azul-alberto-gomez\"><img alt=\"\" src=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-ELADIO-VERA.jpg\" data-image=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/extranjeros-cruz-azul-ELADIO-VERA.jpg\" data-description=\"extranjeros-cruz-azul-ELADIO-VERA\"><\/div>\n        <script>\n        \/\/galeria 1\n        jQuery(document).ready(function(){ \n            var api;\n            api = jQuery(\"#gallery2wM\").unitegallery({\n                carousel_autoplay: false\n            }); \n        });\n        <\/script>\n        \n<p>Para la temporada 1971-72, la <a href=\"http:\/\/www.futboltotal.com.mx\/equipos\/cruz-azul\/\" target=\"_blank\"><em>Maquina<\/em> de <strong>Cruz Azul<\/strong><\/a>\u00a0ya contaba con dos t\u00edtulos de liga. Y si era un equipo poderoso, la llegada de los cuatro jugadores extranjeros lo hizo todav\u00eda m\u00e1s, gracias a que se adaptaron r\u00e1pidamente al club: \u201cNos unimos a flamantes jugadores mexicanos como Javier Guzm\u00e1n, H\u00e9ctor Pulido, Fernando Bustos, Ces\u00e1reo Victorino, entre otros\u201d, recuerda el <em>Hijitus<\/em> G\u00f3mez.<\/p>\n<p>Ese plantel, dirigido por Ra\u00fal C\u00e1rdenas, consigui\u00f3 un r\u00e9cord que sigue vigente en el futbol mexicano: 10 victorias consecutivas (entre las jornadas 8 y 17). El club termin\u00f3 la fase regular en primer lugar de su grupo y calific\u00f3 a la semifinal, en la que elimin\u00f3 a Guadalajara con un 2-1 global.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/2016\/04\/las-emociones-la-copa-mx\/\">VER M\u00c1S: Las EMOCIONES de\u2026 \u00a1la Copa MX!<\/a><\/strong><\/span><\/p>\n<p>La Final fue contra Am\u00e9rica a un partido y en el estadio Azteca, la casa los <em>Cremas<\/em>, en donde los <em>cementeros<\/em> se hicieron hu\u00e9spedes a partir de esa temporada. El triunfo del <strong>Cruz Azul<\/strong> fue contundente: 4-1.\u00a0\u201cTen\u00edamos un esp\u00edritu ganador\u201d, detalla G\u00f3mez. De eso qued\u00f3 constancia con la conquista de los t\u00edtulos de las campa\u00f1as 1972-73 y 1973-74.<\/p>\n<p>\u201cSin duda la llegada de Alberto Quintano, Miguel Mar\u00edn, Eladio Vera y Alberto <em>Hijitus<\/em> G\u00f3mez fue muy acertada. Todos hicimos un gran grupo de jugadores y seres humanos\u201d, asegura el mexicano Horacio L\u00f3pez Salgado, quien era delantero y que tambi\u00e9n lleg\u00f3 en aquella memorable campa\u00f1a 1971-72.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia convirti\u00f3 en \u00edconos a aquellos cuatro for\u00e1neos<\/p>\n","protected":false},"author":127,"featured_media":386617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2198,3845,5950],"tags":[5962],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/386336"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=386336"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/386336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/386617"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=386336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=386336"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=386336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}