{"id":387064,"date":"2016-04-10T15:33:27","date_gmt":"2016-04-10T21:33:27","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=387064"},"modified":"2016-04-10T18:30:05","modified_gmt":"2016-04-11T00:30:05","slug":"en-vivo-puebla-vs-chivas-liga-mx","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-mexicano\/en-vivo-puebla-vs-chivas-liga-mx\/2016\/04","title":{"rendered":"AS\u00cd SE VIVI\u00d3 | Puebla 0-3 Chivas | Liga MX"},"content":{"rendered":"<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">.<a href=\"https:\/\/twitter.com\/PueblaFC\">@PueblaFC<\/a> 0-3 <a href=\"https:\/\/twitter.com\/Chivas\">@Chivas<\/a> resultado con el que <a href=\"https:\/\/twitter.com\/Chivas\">@Chivas<\/a> se mete a Zona de Clasificaci\u00f3n a la <a href=\"https:\/\/twitter.com\/hashtag\/J13CL2016?src=hash\">#J13CL2016<\/a><a href=\"https:\/\/twitter.com\/hashtag\/ElFutbolTeMueve?src=hash\">#ElFutbolTeMueve<\/a> <a href=\"https:\/\/t.co\/gnyLKFSIvw\">pic.twitter.com\/gnyLKFSIvw<\/a><\/p>\n<p>\u2014 LIGA Bancomer MX (@LIGABancomerMX) <a href=\"https:\/\/twitter.com\/LIGABancomerMX\/status\/719311504030306305\">10 de abril de 2016<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"color: #ff0000;\">90:00<\/span>\u00a0+3 \u00a1Termina el partido!<\/p>\n<p><span style=\"color: #ff0000;\">90:00<\/span> Se agregan\u00a0tres minutos.<\/p>\n<p><span style=\"color: #ff0000;\">89:00\u00a0<\/span>\u00a1Expulsi\u00f3n\u00a0para el <em>Chavo<\/em>\u00a0Alustiza, jugador de <strong>Puebla<\/strong>!<\/p>\n<p><span style=\"color: #ff0000;\">86:48<\/span>\u00a0Omar Bravo marca el tercero del <em>Reba\u00f1o<\/em>.\u00a0Emotivo el festejo del <em>Mochiteco<\/em>, quien\u00a0fue a celebrar con Mat\u00edas Almeyda.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\"><p>\n\u00bfTe lo perdiste? Aqu\u00ed est\u00e1 el 3er GOL de <a href=\"https:\/\/twitter.com\/Chivas\">@Chivas<\/a> en donde Omar Bravo anota el 0-3 sobre <a href=\"https:\/\/twitter.com\/PueblaFC\">@PueblaFC<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ElFutbolTeMueve?src=hash\">#ElFutbolTeMueve<\/a> <a href=\"https:\/\/t.co\/iuiKeALDqI\">pic.twitter.com\/iuiKeALDqI<\/a><\/p>\n<p>\u2014 LIGA Bancomer MX (@LIGABancomerMX) <a href=\"https:\/\/twitter.com\/LIGABancomerMX\/status\/719312664468398080\">10 de abril de 2016<\/a>\n<\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"color: #ff0000;\">86:48<\/span>\u00a0Goooooooooooool de\u00a0<strong>Chivas<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\">86:00<\/span>\u00a0CAMBIO de\u00a0<strong>Chivas<\/strong>: sale Orbel\u00edn Pineda,\u00a0entra\u00a0Michael P\u00e9rez.<\/p>\n<p><span style=\"color: #ff0000;\">80:20<\/span> \u00a1Falla la <em>Chofis<\/em>! Villase\u00f1or ataja el penal.<\/p>\n<p><span style=\"color: #ff0000;\">79:00<\/span> \u00a1Penal a favor de <strong>Chivas<\/strong>! Expulsi\u00f3n para Patricio Araujo, jugador\u00a0de <strong>Puebla<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\">78:00<\/span>\u00a0CAMBIO de <strong>Chivas<\/strong>: sale\u00a0\u00c1ngel Zald\u00edvar,\u00a0entran Omar Bravo.<\/p>\n<p><span style=\"color: #ff0000;\">72:00<\/span> CAMBIO de\u00a0<strong>Puebla<\/strong>: sale \u00c1lvaro Navarro, entra Jer\u00f3nimo Amione.<\/p>\n<p><span style=\"color: #ff0000;\">70:22<\/span>\u00a0AMONESTACI\u00d3N para \u00c1lvaro Navarro, jugador de\u00a0<strong>Puebla<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\">67:40<\/span>\u00a0Brillante conducci\u00f3n del <em>Conejito<\/em>\u00a0Brizuela que filtra a \u00c1ngel Zald\u00edvar, quien define de excelente manera ante la salida del portero poblano.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\"><p>G\u26bd\ufe0f\u26bd\ufe0f\u26bd\ufe0fL de <a href=\"https:\/\/twitter.com\/Chivas\">@Chivas<\/a> \u00c1ngel Zald\u00edvar remata dentro del \u00e1rea y anota el 2-0 sobre <a href=\"https:\/\/twitter.com\/PueblaFC\">@PueblaFC<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/J13CL2016?src=hash\">#J13CL2016<\/a><a href=\"https:\/\/twitter.com\/hashtag\/ElFutbolTeMueve?src=hash\">#ElFutbolTeMueve<\/a> <a href=\"https:\/\/t.co\/XGj1amQau8\">pic.twitter.com\/XGj1amQau8<\/a><\/p>\n<p>\u2014 LIGA Bancomer MX (@LIGABancomerMX) <a href=\"https:\/\/twitter.com\/LIGABancomerMX\/status\/719306554839707648\">10 de abril de 2016<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"color: #ff0000;\">67:40<\/span> Goooooooooooool de <strong>Chivas<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\">65:40<\/span>\u00a0La <em>Chofis<\/em> entra al campo. \u00bfVolver\u00e1 a disfrazarse de <em>crack<\/em>?<\/p>\n<p><span style=\"color: #ff0000;\">65:40<\/span> Cambio de\u00a0<strong>Chivas<\/strong>:\u00a0sale Carlos Pe\u00f1a y entra Javier Eduardo L\u00f3pez.<\/p>\n<p><span style=\"color: #ff0000;\">64:00<\/span> Mat\u00edas Alustiza elude rivales\u00a0y mand\u00f3 disparo de larga distancia que se va por encima de la caba\u00f1a de Rodolfo Cota.<\/p>\n<p><span style=\"color: #ff0000;\">60:50<\/span>\u00a0AMONESTACI\u00d3N para Carlos Cisneros, jugador de\u00a0<strong>Chivas<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\">59:00<\/span>\u00a0CAMBIO de <strong>Puebla<\/strong>. Doble ajuste:\u00a0salen\u00a0David Toledo y Dami\u00e1n Escudero, entran Flavio Santos y Jes\u00fas Vald\u00e9z.<\/p>\n<p><span style=\"color: #ff0000;\">58:20<\/span> \u00a1Poste! Salcido estrella su disparo en el poste. <strong>Chivas<\/strong> cerca del segundo.<\/p>\n<p><span style=\"color: #ff0000;\">56:10<\/span>\u00a0<strong>Puebla<\/strong>\u00a0llega al \u00e1rea de <strong>Chivas<\/strong>. Segundos despu\u00e9s, el <em>Reba\u00f1o<\/em> llega al \u00e1rea poblana. Partido\u00a0atractivo.<\/p>\n<p><span style=\"color: #ff0000;\">52:00<\/span>\u00a0AMONESTACI\u00d3N para Patricio Araujo, jugador de\u00a0<strong>Puebla<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\">51:00<\/span>\u00a0<em>Gullit<\/em> Pe\u00f1a ingresa al \u00e1rea y cae tras ligero contacto del <em>Pato<\/em> Araujo. El silbante no sanciona.<\/p>\n<p><span style=\"color: #ff0000;\">51:00<\/span>\u00a0Los primeros minutos del segundo tiempo mantienen la\u00a0esencia\u00a0del primero. <strong>Chivas<\/strong> con ligero dominio, con llegadas sobre el \u00e1rea rival, pero sin certeza en el \u00faltimo tercio del campo.<\/p>\n<p><span style=\"color: #ff0000;\">46:20<\/span>\u00a0La defensa de <strong>Puebla<\/strong> manda a tiro de esquina.<\/p>\n<p><span style=\"color: #ff0000;\">45:00<\/span> \u00a1Inicia el segundo tiempo!<\/p>\n<p><span style=\"color: #ff0000;\">45:00<\/span>\u00a0+1\u00a0Termina el primer tiempo&#8230;<\/p>\n<p><span style=\"color: #ff0000;\">45:00<\/span> Se agrega un minuto.<\/p>\n<p><span style=\"color: #ff0000;\">44:00<\/span>\u00a0P\u00e9simo disparo de Orbel\u00edn Pineda. <strong>Chivas<\/strong> llega, pero falta precisi\u00f3n en el \u00faltimo toque.<\/p>\n<p><a href=\"http:\/\/www.futboltotal.com.mx\/2016\/04\/en-vivo-puebla-vs-chivas-liga-mx\/en-vivo-puebla-chivas-clausura-2016-2\/\" rel=\"attachment wp-att-387487\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-387487\" src=\"http:\/\/www.futboltotal.com.mx\/wp-content\/uploads\/2016\/04\/EN-VIVO-puebla-chivas-clausura-2016-2.jpg\" alt=\"EN-VIVO-puebla-chivas-clausura-2016-2\" srcset=\"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/EN-VIVO-puebla-chivas-clausura-2016-2.jpg 820w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/EN-VIVO-puebla-chivas-clausura-2016-2-300x200.jpg 300w, http:\/\/desarrollo.grupomedios.com\/futbol\/wp-content\/uploads\/2016\/04\/EN-VIVO-puebla-chivas-clausura-2016-2-768x512.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/a><\/p>\n<p><span style=\"color: #ff0000;\">40:24<\/span>\u00a0Cota toma el bal\u00f3n\u00a0en el \u00e1rea chica y corta el tibio arribo poblano.<\/p>\n<p><span style=\"color: #ff0000;\">39:10<\/span> Pineda culmina con disparo a porter\u00eda una notable jugada colectiva del <em>Reba\u00f1o<\/em>. El disparo se fue por encima del arco.<\/p>\n<p><span style=\"color: #ff0000;\">35:00<\/span> Carlos Cisneros saca disparo desde los linderos del \u00e1rea, pero el esf\u00e9rico se va\u00a0encima del arco rival.<\/p>\n<p><span style=\"color: #ff0000;\">28:22<\/span>\u00a0Ahora es el quien\u00a0<em>Conejo<\/em> Brizuela dispara de larga distancia, pero el bal\u00f3n sale ligeramente desviado.<\/p>\n<p><span style=\"color: #ff0000;\">26:55<\/span>\u00a0Nueva llegada de las <strong>Chivas<\/strong>. El disparo del <em>Chapito<\/em> sale a las mano de Villase\u00f1or.<\/p>\n<p><span style=\"color: #ff0000;\">26:00<\/span>\u00a0Duelo atractivo en el Cuauht\u00e9moc. Ambos conjuntos buscan el arco rival.<\/p>\n<p><span style=\"color: #ff0000;\">22:55<\/span> Remate de cabeza de Alustiza que detiene Cota.<\/p>\n<p><span style=\"color: #ff0000;\">20:15<\/span>\u00a0Buena conducci\u00f3n de Pineda,\u00a0quien deja atr\u00e1s a los rivales y cede\u00a0para el <em>Gullit<\/em>, quien saca disparo de\u00a0que pasa apenas arriba de la porter\u00eda poblana.<\/p>\n<p><span style=\"color: #ff0000;\">16:53<\/span>\u00a0El <em>Reba\u00f1o<\/em> vuelve a tocar la puerta de la <em>Franja<\/em>. Villase\u00f1or pone calma.<\/p>\n<p><span style=\"color: #ff0000;\">14:52<\/span>\u00a0<strong>Puebla<\/strong>, cerquita. Arribo peligro de los poblanos. El disparo de Navarro pasa por un costado del\u00a0arco <em>rojiblanco<\/em>.<\/p>\n<p><span style=\"color: #ff0000;\">14:00<\/span>\u00a0<strong>Chivas<\/strong> presiona la salida del rival. Hasta ahora, parece mejor el <em>Reba\u00f1o<\/em>.<\/p>\n<p><span style=\"color: #ff0000;\">10:00<\/span>\u00a0Disparo de Luis Robles desde afuera del \u00e1rea, pero el bal\u00f3n se va muy por encima del arco de Rodolfo Cota.<\/p>\n<p><span style=\"color: #ff0000;\">06:00<\/span> AMONESTACI\u00d3N para Jair Pereira, jugador de <strong>Chivas<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\">04:00<\/span> Carlos Cisneros roba un bal\u00f3n en la salida de Puebla, conduce hacia el \u00e1rea rival y saca un derechazo de larga distancia que se incrusta en el \u00e1ngulo.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\"><p>\nG\u26bd\ufe0f\u26bd\ufe0fL de <a href=\"https:\/\/twitter.com\/Chivas\">@Chivas<\/a> Carlos Cisneros anota su 3er G\u26bd\ufe0fL con <a href=\"https:\/\/twitter.com\/Chivas\">@Chivas<\/a> y pone el 0-1 sobre <a href=\"https:\/\/twitter.com\/PueblaFC\">@PueblaFC<\/a><a href=\"https:\/\/twitter.com\/hashtag\/ElFutbolTeMueve?src=hash\">#ElFutbolTeMueve<\/a> <a href=\"https:\/\/t.co\/8pKBQBJqRV\">pic.twitter.com\/8pKBQBJqRV<\/a><\/p>\n<p>\u2014 LIGA Bancomer MX (@LIGABancomerMX) <a href=\"https:\/\/twitter.com\/LIGABancomerMX\/status\/719287214018965504\">10 de abril de 2016<\/a>\n<\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"color: #ff0000;\">04:00<\/span>\u00a0\u00a1Gooooooooooool de <strong>Chivas<\/strong>!<\/p>\n<p><span style=\"color: #ff0000;\">03:05<\/span>\u00a0\u00a1Cerca, <strong>Chivas<\/strong>! Zald\u00edvar dispara de manera incomoda y el bal\u00f3n sale desviado.<\/p>\n<p><span style=\"color: #ff0000;\">01:00<\/span> \u00bfFalta de Araujo sobre el <em>Gullit<\/em> Pe\u00f1a dentro del \u00e1rea?\u00a0Nada, el \u00e1rbitro no marca nada.<\/p>\n<p><span style=\"color: #ff0000;\">00:00<\/span> \u00a1Arranca el partido!<\/p>\n<p>El \u00e1rbitro del partido ser\u00e1 Erick Yair Miranda.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\"><p>?? \u00a1El Cuauht\u00e9moc ya empieza a pintarse Rojiblanco! ?\u26aa\ufe0f? <a href=\"https:\/\/t.co\/I6D9oOnbjD\">pic.twitter.com\/I6D9oOnbjD<\/a><\/p>\n<p>\u2014 CHIVAS (@Chivas) <a href=\"https:\/\/twitter.com\/Chivas\/status\/719274866789064704\">10 de abril de 2016<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\"><p>\n\u00bfLinda panor\u00e1mica no??<a href=\"https:\/\/twitter.com\/hashtag\/PorSiemprePoblano?src=hash\">#PorSiemprePoblano<\/a> ?? <a href=\"https:\/\/t.co\/VXbAN9dZNO\">pic.twitter.com\/VXbAN9dZNO<\/a><\/p>\n<p>\u2014 Club Puebla (@PueblaFC) <a href=\"https:\/\/twitter.com\/PueblaFC\/status\/719272846170542080\">10 de abril de 2016<\/a>\n<\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p>Alineaci\u00f3n <b>CHIVAS<\/b>:\u00a0Rodolfo Cota, Jes\u00fas S\u00e1nchez, Jair Pereira, Carlos Salcedo, Edwin Hern\u00e1ndez, Carlos Salcido, Orbel\u00edn Pineda, Isaac Brizuela, Carlos Cisneros, Carlos Pe\u00f1a y \u00c1ngel Zald\u00edvar.<\/p>\n<p>Alineaci\u00f3n <strong>PUEBLA<\/strong>: Fabi\u00e1n Villase\u00f1or, \u00d3scar Rojas, Patricio Araujo, Robert Herrera, Carlos Guti\u00e9rrez, Luis Robles, David Toledo, Dami\u00e1n Escudero, Christian Berm\u00fadez, Gustavo Alustiza y \u00c1lvaro Navarro.<\/p>\n<p>Con la goleada que le propinaron a los Pumas de la UNAM, las\u00a0<strong><a href=\"http:\/\/futboltotal.com.mx\/equipos\/guadalajara\/\" target=\"_blank\">Chivas del Guadalajara<\/a><\/strong> quieren ampliar su racha ante un mermado <strong><a href=\"http:\/\/futboltotal.com.mx\/equipos\/puebla\/\" target=\"_blank\">Puebla<\/a><\/strong>, que por su parte anhela regresar a la senda del triunfo en el marco de la <strong>jornada 13<\/strong> del <strong>Clausura 2016<\/strong>.<\/p>\n<p>El estadio Cuauht\u00e9moc albergar\u00e1 el partido que comenzar\u00e1 este domingo en punto de las 17:00 horas, ah\u00ed el <em>Reba\u00f1o Sagrado<\/em> llega con los \u00e1nimos renovados, situaci\u00f3n que intentar\u00e1 demostrar en el campo de juego.<\/p>\n<p>\u201cFue importante c\u00f3mo se gan\u00f3 el partido pasado, por lo que pensamos en mantener esa l\u00ednea, estar m\u00e1s concentrados para ir a <strong>Puebla<\/strong>, una cancha complicada, para no recibir gol y as\u00ed estar m\u00e1s cerca del triunfo. El equipo se ha visto bien en la zona defensiva y todos han hecho una gran labor para colaborar en eso, eso nos ha permitido mantener el cero un par de veces, es algo muy importante&#8221;, explic\u00f3 el portero de <strong>Chivas<\/strong>, Rodolfo Cota.<\/p>\n<p>Uno los mayores alicientes para ambas escuadras es que ya no se deben de preocupar por el descenso, al menos este semestre pues el tema ya se resolvi\u00f3 con la despedida de Dorados. Ante este panorama, la <em>Franja<\/em> y Guadalajara deben aprovechar y apuntar a liguilla.<\/p>\n<p>\u00bfCu\u00e1l es tu pron\u00f3stico para el <strong>Puebla vs. Chivas<\/strong>, <em>crack<\/em>?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Reba\u00f1o quiere mantenerse en la senda del triunfo<\/p>\n","protected":false},"author":20,"featured_media":387507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2198,3845],"tags":[70,5969],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/387064"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=387064"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/387064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/387507"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=387064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=387064"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=387064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}