{"id":393613,"date":"2016-05-02T21:14:48","date_gmt":"2016-05-03T03:14:48","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=393613"},"modified":"2016-05-03T12:39:04","modified_gmt":"2016-05-03T18:39:04","slug":"cual-club-sera-proximo-campeon","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-internacional\/cual-club-sera-proximo-campeon\/2016\/05","title":{"rendered":"Y despu\u00e9s del Leicester&#8230; \u00bfQui\u00e9n ser\u00e1 campe\u00f3n?"},"content":{"rendered":"<p>Las ligas m\u00e1s populares del planeta est\u00e1n a las puertas de un ep\u00edlogo en el que habr\u00e1 lucha sin tregua, de poder a poder, entre los punteros de la clasificaci\u00f3n por el t\u00edtulo de la temporada 2015-16. El t\u00edtulo ya est\u00e1 en la vitrina del Olympiacos griego, el PSG franc\u00e9s, el Juventus italiano y el \u00faltimo en conseguirlo ha sido el <strong>Leicester City, <\/strong>que gan\u00f3 su primer t\u00edtulo de la Premier League.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong><a style=\"color: #3366ff;\" href=\"http:\/\/www.futboltotal.com.mx\/2016\/05\/hazard-cumple-promesa-a-liecester\/\">LEER M\u00c1S: \u00a1Hazard cumple promesa y hace al Leicester campe\u00f3n!<\/a><\/strong><\/span><\/p>\n<p>Antes de que vuelva a rodar el bal\u00f3n el fin de semana, en Futbol Total te contamos las posibilidades que tienen los clubes de otras latitudes para coronarse. \u00bfQui\u00e9nes ser\u00e1n los pr\u00f3ximos campeones de Europa?<\/p>\n<p><em>IMAGEN INTERACTIVA | Sit\u00faa el curso o dedo \u00edndice sobre la imagen para ver la informaci\u00f3n.<\/em><\/p>\n<p><img decoding=\"async\" class=\"alwaysThinglink\" style=\"max-width: 100%;\" src=\"\/\/cdn.thinglink.me\/api\/image\/784125493476589568\/1024\/10\/scaletowidth#tl-784125493476589568;1043138249'\" alt=\"Y despu\u00e9s del Leicester&#8230; \u00bfQui\u00e9n ser\u00e1 campe\u00f3n? 0\" \/><script src=\"\/\/cdn.thinglink.me\/jse\/embed.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aun pelean por el t\u00edtulo varios clubes del planeta futbol <\/p>\n","protected":false},"author":20,"featured_media":393623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3839,3846],"tags":[],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/393613"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=393613"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/393613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/393623"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=393613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=393613"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=393613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}