{"id":413861,"date":"2016-07-28T10:08:31","date_gmt":"2016-07-28T15:08:31","guid":{"rendered":"http:\/\/www.futboltotal.com.mx\/?p=413861"},"modified":"2016-07-28T10:08:31","modified_gmt":"2016-07-28T15:08:31","slug":"manchester-city-doblega-al-dortmund","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-internacional\/manchester-city-doblega-al-dortmund\/2016\/07","title":{"rendered":"Primer triunfo de Guardiola con el Manchester City"},"content":{"rendered":"<p>El <strong>Manchester City<\/strong> entrenado desde esta temporada por <em>Pep<\/em> <strong>Guardiola<\/strong> se impuso en los penaltis al <strong>Borussia Dortmund<\/strong> (6-5) tras acabar 1-1 en el tiempo reglamentario, en un encuentro amistoso disputado en la ciudad china de Shenzhen y presidido por la fuerte humedad.<\/p>\n<p>El calor reinante en la ciudad del delta del R\u00edo Perla, vecina a Hong Kong, desluci\u00f3 algo el juego de ingleses y alemanes, aunque fueron los <em>Sky Blues<\/em>\u00a0los que m\u00e1s hicieron por animar el encuentro en sus inicios, gracias a una buena ocasi\u00f3n\u00a0que Dembele tuvo en el minuto 6 para el Dortmund, y que Otamendi supo atajar desde la defensa.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong>LEER M\u00c1S: Todas las noticias de futbol internacional<\/strong><\/span><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ibxgjVeX1O0\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Pero fue en la segunda parte cuando lleg\u00f3 lo mejor cuando llegaron los goles en jugadas aisladas. El primero de ellos para el City en el minuto 78, obra de Ag\u00fcero a pase de Silva en el \u00e1rea chica.<\/p>\n<p>Fue ya en el minuto cinco de descuento, cuando el Dortmund igual\u00f3 con un tanto de Pulisic tras un c\u00f3rner sacado en corto que acab\u00f3 en un lanzamiento raso del estadounidense que cogi\u00f3 desprevenido al arquero.<\/p>\n<p>Tras los 90 minutos reglamentarios se prescindi\u00f3 de prorrogas y se pas\u00f3 directamente a los lanzamientos de penalti, en los que Gunn, el portero suplente del Manchester, tuvo dos excelentes paradas ante Larsen y el espa\u00f1ol Merino, lo que propici\u00f3 la victoria del City (Sterling fue el \u00fanico del equipo ingl\u00e9s que fall\u00f3).<\/p>\n<p>El partido finaliza la gira china del City de Guardiola, algo descafeinada debido a la cancelaci\u00f3n, el pasado lunes, de un esperado amistoso entre los citizens y el Manchester United de Jos\u00e9 Mourinho, que iba a disputarse en Pek\u00edn pero no pudo jugarse debido a las intensas lluvias que azotaron la capital.<\/p>\n<p>El Borussia venci\u00f3 en el otro partido del triangular al United por 4-1 en Shangh\u00e1i, el pasado 22 de julio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Citizens le pegan en penales al Borussia Dortmund <\/p>\n","protected":false},"author":20,"featured_media":413864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3839,3846,5951],"tags":[6047,5993],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/413861"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=413861"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/413861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/413864"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=413861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=413861"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=413861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}