{"id":454731,"date":"2017-01-18T15:07:16","date_gmt":"2017-01-18T21:07:16","guid":{"rendered":"https:\/\/www.futboltotal.com.mx\/?p=454731"},"modified":"2017-01-18T15:07:16","modified_gmt":"2017-01-18T21:07:16","slug":"liga-mx-solicita-la-venta-chiapas","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/destacado-home\/liga-mx-solicita-la-venta-chiapas\/2017\/01","title":{"rendered":"Liga MX solicita la venta de Chiapas"},"content":{"rendered":"<p>Chiapas sigue involucrado en adeudos a sus futbolistas y cuerpo t\u00e9cnico del equipo. Es por esto que la Liga MX ha llamado a conferencia de prensa esta tarde con Enrique Bonilla, en donde se habl\u00f3 sobre la actual situaci\u00f3n que vive el club sure\u00f1o.<\/p>\n<p>La Liga Mx inform\u00f3 que el due\u00f1o de Chiapas, Carlos L\u00f3pez Chargoy, ya tiene fecha limite para vender al equipo y hacerse a un lado para que su situaci\u00f3n pueda mejorar.<\/p>\n<blockquote><p>&#8220;Ya se le solicit\u00f3 al se\u00f1or Carlos L\u00f3pez Chargoy que debe deshacerse del Club Jaguares. La fecha limite es la siguiente la siguiente temporada&#8221;, declar\u00f3 Enrique Bonilla ante los medios.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">Se le solicit\u00f3 al se\u00f1or Chargoy que debe deshacerse del Club Jaguares de Chiapas, para la siguiente temporada.<\/p>\n<p>\u2014 LIGA Bancomer MX (@LIGABancomerMX) <a href=\"https:\/\/twitter.com\/LIGABancomerMX\/status\/821805882946240521\">18 de enero de 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>El presidente de la Liga MX, coment\u00f3 el motivo por el cual Jaguares tuvo la oportunidad de jugar la presente temporada.<\/p>\n<blockquote><p>&#8220;Jaguares cumpli\u00f3 con todos sus pagos y es por eso que pudo iniciar el Clausura 2017. Para poder participar en el r\u00e9gimen de transferencias, deben estar al corriente de sus pagos&#8221;, coment\u00f3 Bonilla.<\/p><\/blockquote>\n<p>Chiapas tiene hasta el pr\u00f3ximo 30 de enero para pagar los adeudos que tiene con los futbolistas correspondientes.<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">El 30 de enero es el \u00faltimo d\u00eda que tiene Jaguares para cubrir los adeudos con los jugadores correspondientes.<\/p>\n<p>\u2014 LIGA Bancomer MX (@LIGABancomerMX) <a href=\"https:\/\/twitter.com\/LIGABancomerMX\/status\/821806877382017024\">18 de enero de 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Liga MX dio conferencia de prensa en las instalaciones de la Federaci\u00f3n Mexicana de Futbol. <\/p>\n","protected":false},"author":20,"featured_media":454732,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,2198,3845],"tags":[5964,1091,64,2902],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/454731"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=454731"}],"version-history":[{"count":0,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/454731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/454732"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=454731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=454731"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=454731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}