{"id":495347,"date":"2017-08-21T20:08:01","date_gmt":"2017-08-22T01:08:01","guid":{"rendered":"https:\/\/www.futboltotal.com.mx\/?p=495347"},"modified":"2017-08-21T20:08:01","modified_gmt":"2017-08-22T01:08:01","slug":"tim-howard-hace-oso-en-la-mls","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-internacional\/tim-howard-hace-oso-en-la-mls\/2017\/08","title":{"rendered":"Tim Howard hace el oso en la MLS"},"content":{"rendered":"<p>El guardameta del <strong>Colorado Rapids<\/strong> y de la <strong>Selecci\u00f3n de Estados Unidos, Tim Howard,<\/strong> cometi\u00f3 tremendo oso en la <strong>MLS<\/strong> y concedi\u00f3 un incre\u00edble autogol, situaci\u00f3n que los coloca en la pen\u00faltima posici\u00f3n de la tabla general de la <strong>Conferencia Oeste<\/strong>, con 22 unidades.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.futboltotal.com.mx\/2017\/08\/gignac-conocio-a-su-tocayo-en-el-zoologico\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #333399;\">VER M\u00c1S:\u00a0Gignac conoci\u00f3 a su tocayo en el zool\u00f3gico<\/span><\/a><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/HJk673isbiQ?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Con el error garrafal del arquero, su equipo termin\u00f3 cayendo por la m\u00ednima diferencia, luego de que <strong>Jared Watts<\/strong> le enviara un pase de tr\u00e1mite, pensando que el guardameta se encontraba cerca de su porter\u00eda; sin embargo, para sorpresa de \u00e9l no fue as\u00ed y por m\u00e1s que estir\u00f3 la pierna para evitar la ca\u00edda de su marco, no logr\u00f3 impedir que el esf\u00e9rico se colara al fondo de la red.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.futboltotal.com.mx\/2017\/08\/wayne-rooney-marco-gol-200-y-va-tras-record-shearer\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #333399;\">VER M\u00c1S:\u00a0Wayne Rooney marc\u00f3 su gol 200 y va tras r\u00e9cord de Shearer<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El oso de la semana es para Tim Howard del Colorado Rapids<\/p>\n","protected":false},"author":20,"featured_media":441530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5419,3839,9635],"tags":[6526,195,1333],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/495347"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=495347"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/495347\/revisions"}],"predecessor-version":[{"id":495348,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/495347\/revisions\/495348"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/441530"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=495347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=495347"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=495347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}