{"id":499161,"date":"2017-09-10T17:32:23","date_gmt":"2017-09-10T22:32:23","guid":{"rendered":"https:\/\/www.futboltotal.com.mx\/?p=499161"},"modified":"2017-09-10T20:36:44","modified_gmt":"2017-09-11T01:36:44","slug":"santos-vs-toluca-apertura-2017-liga-mx-minuto-a-minuto","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-mexicano\/santos-vs-toluca-apertura-2017-liga-mx-minuto-a-minuto\/2017\/09","title":{"rendered":"MINUTO A MINUTO | Santos vs Toluca | Apertura 2017"},"content":{"rendered":"<p><strong>Santos Laguna<\/strong> recibe la visita del <strong>Toluca<\/strong> en el duelo que cierra la fecha 8 del Torneo Apertura 2017 de la <strong>Liga MX<\/strong>.<\/p>\n<p>Los laguneros ya saben lo que es ganar en el torneo, despu\u00e9s de su triunfo de la jornada pasada en cancha del Le\u00f3n, y ahora quieren repetir con el que ser\u00eda su primer triunfo en casa.<\/p>\n<iframe src=\"https:\/\/en-vivo.futboltotal.com.mx\/embed.php\/?id=272\" width=\"100%\" id=\"frame_minuto\"><\/iframe>\n<p style=\"text-align: center;\"><span style=\"color: #333399;\"><a style=\"color: #333399;\" href=\"https:\/\/www.futboltotal.com.mx\/2017\/09\/pumas-vs-tijuana-apertura-2017-liga-mx-minuto-a-minuto\/\">VER M\u00c1S:\u00a0<span class=\"item-title\">MINUTO A MINUTO | Pumas vs Tijuana, a recuperar el camino<\/span><\/a><\/span><\/p>\n<p>Los Diablos Rojos han sufrido en calidad de visitante en lo que va del torneo, la mayor\u00eda de sus puntos los han logrado en el Nemesio Diez, pero enfrentan a un viejo conocido, Jos\u00e9 Manuel de la Torre.<\/p>\n<p>Desde el Apertura 2014, Santos no ha podido llevarse la victoria en casa frente a Toluca, pero el paso intermitente de los Diablos podr\u00eda terminar con la racha de los laguneros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los laguneros ya conocieron el camino del triunfo y ahora quieren embalarse en el torneo<\/p>\n","protected":false},"author":20,"featured_media":499294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2198,3845],"tags":[64,5972,5975],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/499161"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=499161"}],"version-history":[{"count":3,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/499161\/revisions"}],"predecessor-version":[{"id":499266,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/499161\/revisions\/499266"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/499294"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=499161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=499161"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=499161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}