{"id":499409,"date":"2017-09-11T16:00:16","date_gmt":"2017-09-11T21:00:16","guid":{"rendered":"https:\/\/www.futboltotal.com.mx\/?p=499409"},"modified":"2017-09-12T11:32:45","modified_gmt":"2017-09-12T16:32:45","slug":"201709miguel-layun-inicara-carrera-empresario","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/futbol\/futbol-mexicano\/201709miguel-layun-inicara-carrera-empresario\/2017\/09","title":{"rendered":"Miguel Lay\u00fan iniciar\u00e1 su carrera como empresario"},"content":{"rendered":"<p>A pesar de que hace unos meses se le critic\u00f3 por no estar en su mejor momento, <strong>Miguel Lay\u00fan<\/strong> poco a poco va retomando la confianza, primero al ser titular con el Porto y ahora al iniciar su carrera como empresario.<\/p>\n<p><strong>Lay\u00fan<\/strong> ya disput\u00f3 90 minutos con los Dragones y espera seguir as\u00ed para poder regresar a las convocatorias de la Selecci\u00f3n Mexicana, de la que estuvo ausente ante Panam\u00e1 y Costa Rica.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/www.futboltotal.com.mx\/2017\/09\/los-reencuentros-esta-champions-league\/\">VER M\u00c1S: Los reencuentros de esta Champions League<\/a><\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\">\n<p lang=\"es\" dir=\"ltr\">Feliz de trabajar y luchar con mis compa\u00f1eros. Gran victoria en casa que nos mantiene en el rumbo hacia el objetivo. <a href=\"https:\/\/t.co\/vl4ipMQOnB\">pic.twitter.com\/vl4ipMQOnB<\/a><\/p>\n<p>&mdash; Miguel Layun (@Miguel_layun) <a href=\"https:\/\/twitter.com\/Miguel_layun\/status\/906655980611665925\">September 9, 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Es por ello que ahora el jugador del <strong>Porto<\/strong> ha presumido su nuevo negocio, pues demostr\u00f3 que es un gran emprendedor y a trav\u00e9s de su cuenta de Instagram comparti\u00f3 su nueva empresa de caf\u00e9.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 658px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-version=\"7\">\n<div style=\"padding: 8px;\">\n<div style=\"background: #F8F8F8; line-height: 0; margin-top: 40px; padding: 33.19444444444444% 0; text-align: center; width: 100%;\"><\/div>\n<p style=\"margin: 8px 0 0 0; padding: 0 4px;\"><a style=\"color: #000; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none; word-wrap: break-word;\" href=\"https:\/\/www.instagram.com\/p\/BV7TPCXgKOp\/\" target=\"_blank\" rel=\"noopener noreferrer\">Antes de llegar, hab\u00eda que visualizarse. Hoy @miguel_layun est\u00e1 en la semifinal de la copa confederaciones!, ayer estaba inspir\u00e1ndose tomando un CAF\u00c9 19. #cafe19 #cafe #mexico<\/a><\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\">Una publicaci\u00f3n compartida por CAF\u00c9 19 (@cafe19mx) el <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2017-06-29T14:18:47+00:00\">29 de Jun de 2017 a la(s) 7:18 PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async defer src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Baj\u00f3 la etiqueta de <em>Caf\u00e9 19<\/em>\u00a0y un dibujo del futbolista mexicano, presumi\u00f3 en redes sociales que lo disfrut\u00f3 con unas ricas galletas y el delicioso sabor que tiene. Aqu\u00ed el video de<strong> Lay\u00fan<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/F7snNRzc1Os?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mexicano comparti\u00f3 su nueva empresa.<\/p>\n","protected":false},"author":20,"featured_media":454932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2198],"tags":[3883,1035],"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/499409"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/comments?post=499409"}],"version-history":[{"count":2,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/499409\/revisions"}],"predecessor-version":[{"id":499529,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/posts\/499409\/revisions\/499529"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media\/454932"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/media?parent=499409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/categories?post=499409"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/futbol\/wp-json\/wp\/v2\/tags?post=499409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}