{"id":115300,"date":"2015-12-01T10:00:08","date_gmt":"2015-12-01T16:00:08","guid":{"rendered":"http:\/\/mujerde10.com\/?p=115300"},"modified":"2015-12-01T09:12:51","modified_gmt":"2015-12-01T15:12:51","slug":"5-pasos-que-debes-seguir-para-obtener-un-mejor-trabajo-este-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/vision-de-10\/trabajo\/5-pasos-que-debes-seguir-para-obtener-un-mejor-trabajo-este-2016\/2015\/12\/","title":{"rendered":"5 pasos que debes seguir para obtener un mejor trabajo este 2016"},"content":{"rendered":"<blockquote>\n<p class=\"p1\"><em><span class=\"s1\">\u00a1Tranquila! los finales de a\u00f1o son muy complicados laboralmente hablando, las vacantes son muy escasas y la mayor\u00eda de las empresas no hacen contrataciones. <\/span><span class=\"s1\">Si a\u00fan no encuentras trabajo o est\u00e1s pensando en cambiar el que actualmente tienes, es momento de seguir al pie de la letra estos <strong>5 pasos para que lo logres<\/strong>\u2026 <\/span><\/em><\/p>\n<\/blockquote>\n<p class=\"p1\"><span class=\"s1\"><strong>1. Deja atr\u00e1s malos pensamientos:<\/strong><br \/>\nAcept\u00e9moslo, tal vez te est\u00e9s autosaboteando con pensamientos como: \u201cno soy buena en lo que hago\u201d, \u201ctal vez estoy pidiendo demasiado\u201d, \u201cno me s\u00e9 expresar\u201d, etc\u2026 Lo que debes hacer es tener confianza en ti misma y estar segura de tus habilidades, naturalmente se notar\u00e1 en la entrevista.<\/span><\/p>\n<p class=\"p1\"><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_mmrdc4C59e1rmepxzo1_500.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115319\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_mmrdc4C59e1rmepxzo1_500.gif\" alt=\"tumblr_mmrdc4C59e1rmepxzo1_500\" \/><\/a><\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>2. Redacta adecuadamente tu CV:<\/strong><br \/>\nEs tu carta de presentaci\u00f3n, un buen CV har\u00e1 que te llamen o no, y no hablo de que tengas much\u00edsima experiencia. Busca un dise\u00f1o sencillo y f\u00e1cil de leer, destaca todas tus aptitudes y metas. \u00a1Los de Recursos Humanos es lo primero que ven!<\/span><\/p>\n<p class=\"p1\"><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_n7fx41LV8R1rbgp12o1_500.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115320\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_n7fx41LV8R1rbgp12o1_500.gif\" alt=\"tumblr_n7fx41LV8R1rbgp12o1_500\" \/><\/a><\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>3. Sube tu CV a diferentes plataformas:<\/strong><br \/>\nDale exposici\u00f3n a tu perfil, busca sitios especializados a tu carrera, ya hay cientos de p\u00e1ginas en Facebook buscando un perfil como el tuyo, s\u00f3lo h\u00e1zelos saber.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>4. Toma un curso de idiomas:<\/strong><br \/>\nEl manejo de otro idioma te dar\u00e1 un plus, y el ingl\u00e9s es b\u00e1sico para obtener un trabajo mejor remunerado. \u00a1Si a\u00fan no te has decidido, tienes que tomarlo desde ya! <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>5. Prepara una entrevista de trabajo:<\/strong><br \/>\nTal vez sientas muy nerviosa cuando hablas de frente con alguien. Prepara con anticipaci\u00f3n un speech, no quiere decir que lo aprendas de memoria, simplemente tendr\u00e1s una peque\u00f1a gu\u00eda de respuestas que te dar\u00e1n seguridad.<\/span><\/p>\n<p class=\"p1\"><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_noi2byUY1F1uq16wyo1_500.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115323\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_noi2byUY1F1uq16wyo1_500.gif\" alt=\"tumblr_noi2byUY1F1uq16wyo1_500\" \/><\/a><\/p>\n<p class=\"p3\" style=\"text-align: center;\"><em><span class=\"s1\">\u00a1Ahora que lo sabes! Es momento de salir por ese trabajo que tanto quieres!<\/span><\/em><\/p>\n<p class=\"p3\"><span class=\"s1\">\u00a1Forma parte de los m\u00e1s de 2 millones de egresados en M\u00e9xico, que mejoraron su vida con Harmon Hall!<\/span><\/p>\n<p class=\"p3\"><span class=\"s1\">En 1966, el Instituto Harmon Hall fue fundado con el objetivo de impulsar la cultura de los idiomas en nuestro pa\u00eds. Es la empresa l\u00edder en M\u00e9xico, especializada en la ense\u00f1anza y certificaci\u00f3n del idioma ingl\u00e9s, que adem\u00e1s ha sido reconocida por la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) como una instituci\u00f3n cultural.<\/span><\/p>\n<p class=\"p3\"><span class=\"s1\">Cuenta con cien planteles en la Rep\u00fablica Mexicana, con presencia en m\u00e1s de 50 ciudades, principalmente en el D.F. y \u00c1rea Metropolitana, Nuevo Le\u00f3n, Jalisco, Tamaulipas y Quintana Roo as\u00ed como uno en Guatemala.<\/span><\/p>\n<p class=\"p3\"><span class=\"s1\">El compromiso con sus alumnos los lleva a realizar investigaciones de manera continua a fin de desarrollar un programa efectivo bajo una metodolog\u00eda probada y respaldada por investigaciones mundiales con expertos en la publicaci\u00f3n de textos para la ense\u00f1anza de idiomas. El programa de Harmon Hall est\u00e1 alineado con est\u00e1ndares internacionales como el MCER (Marco Com\u00fan de Referencia para las Lenguas). Su programa cuenta con un corpus ling\u00fc\u00edstico as\u00ed como un sistema integral de aseguramiento de calidad, que le permite detectar y fortalecer las \u00e1reas de mejora y oportunidad en cada alumno, garantizando que el aprendizaje sea real y efectivo para una correcta comunicaci\u00f3n aplicable en toda situaci\u00f3n del d\u00eda a d\u00eda.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: center;\"><span class=\"s1\">Para mayor informaci\u00f3n visita<a href=\"http:\/\/www.harmonhall.com\/\"> www.harmonhall.com<\/a> 01800 422 5292<\/span><\/p>\n<p class=\"p3\"><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/BANNER_PRECIOS_2016-.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-115311 aligncenter\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/BANNER_PRECIOS_2016-.jpg\" alt=\"BANNER_PRECIOS_2016\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Tranquila! los finales de a\u00f1o son muy complicados laboralmente hablando, las vacantes son muy escasas y la mayor\u00eda de las empresas no hacen contrataciones. Si a\u00fan no [&hellip;]<\/p>\n","protected":false},"author":8248,"featured_media":115339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[478,3170,16337],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2015\/12\/5-pasos-que-debes-seguir-para-obtener-un-mejor-trabajo-este-2016.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/115300"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/8248"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=115300"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/115300\/revisions"}],"predecessor-version":[{"id":115341,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/115300\/revisions\/115341"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/115339"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=115300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=115300"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=115300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}