{"id":115806,"date":"2015-12-03T18:00:23","date_gmt":"2015-12-04T00:00:23","guid":{"rendered":"http:\/\/mujerde10.com\/?p=115806"},"modified":"2015-12-28T11:16:23","modified_gmt":"2015-12-28T17:16:23","slug":"5-cosas-de-las-que-no-deberias-sentirte-culpable","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/relax\/ocio\/5-cosas-de-las-que-no-deberias-sentirte-culpable\/2015\/12\/","title":{"rendered":"5 cosas de las que no deber\u00edas sentirte culpable"},"content":{"rendered":"<p style=\"padding-left: 30px;\"><em>Las mujeres somos as\u00ed: llegamos a <strong>sentirnos<\/strong> <strong>culpables<\/strong> de todo lo que nos pasa, de lo que hacemos y hasta de lo que no hacemos. Pues esta costumbre tiene que parar. Sobre todo deja de sentirte mal de estas <strong>5\u00a0cosas:<\/strong>\u00a0<\/em><\/p>\n<ol>\n<li><strong>Consentirte<\/strong> comprando <strong>algo caro<\/strong><\/li>\n<\/ol>\n<p>\u00bfEres una persona que\u00a0sabe ahorrar muy bien? Seguramente cuando ves un abrigo caro o una bolsa hermosa, lo piensas dos veces antes de comprarla. Y si lo haces, te sientes <strong>culpable<\/strong> todo el a\u00f1o. Pues \u00a1no deber\u00edas! No es malo consentirte de vez en cuando y comprar eso que tanto deseas. S\u00f3lo no olvides que todo en exceso es malo.<\/p>\n<p><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_muz9fvUr9f1s9ss8ko1_500.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115832\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_muz9fvUr9f1s9ss8ko1_500.gif\" alt=\"shopping\" \/><\/a><\/p>\n<p style=\"padding-left: 30px;\">2. Salir de la <strong>rutina<\/strong><\/p>\n<p>As\u00ed como gastar dinero en ti misma puede ser una buena idea, tambi\u00e9n lo es permitirte otros placeres aunque no sean tan productivos: duerme un s\u00e1bado hasta medio d\u00eda, \u00a0pasa todo el domingo viendo Netflix o\u00a0pide un d\u00eda\u00a0papas a la francesa en lugar de ensalada. Si <strong>no afectas<\/strong> a nadie con tu decisi\u00f3n y consideras esto como una excepci\u00f3n y no como una regla de vida, \u00a1deber\u00edas hacerlo!<\/p>\n<p><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/ashley-benson-pretty-little-liars-hanna-watching-tv.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115834\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/ashley-benson-pretty-little-liars-hanna-watching-tv.gif\" alt=\"watching tv\" \/><\/a><\/p>\n<p style=\"padding-left: 30px;\">3. No ver a tus <strong>pap\u00e1s<\/strong> tan <strong>frecuentemente<\/strong><\/p>\n<p>Muchas veces por cuestiones de trabajo o de estudios llegamos a mudarnos a estados diferentes o hasta a pa\u00edses distintos de\u00a0donde\u00a0vive nuestra familia. Y es a veces deprimente y dif\u00edcil. La vida va cambiando y a veces nos separa. Es el curso de la vida.<\/p>\n<p>Es importante que entiendas que no puedes detenerte por nadie. No ser\u00eda lo mejor dejar una excelente oportunidad laboral por miedo a alejarte de tu familia. Es mejor establecer fechas importantes, como Navidad, para visitarse y estar en contacto por tel\u00e9fono, internet o infinitas formas. \u00a1No te sientas culpable por perseguir tus sue\u00f1os!<\/p>\n<p><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_inline_neda6ra32P1rkygkg.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115835\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/tumblr_inline_neda6ra32P1rkygkg.gif\" alt=\"family hug\" \/><\/a><\/p>\n<p style=\"padding-left: 30px;\">4.<strong> Terminar una relaci\u00f3n<\/strong><\/p>\n<p>Si no quieres terminar con \u00abfulanito\u00bb por qu\u00e9 te vas a sentir culpable, tienes que dejar de hacerlo. No tiene nada de malo saber qu\u00e9 es lo que queremos para nosotras mismas y si esa persona no cumple con esto, es mejor separarnos. A la larga, ser\u00e1 lo mejor para los dos.<\/p>\n<p><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/Damon-damon-salvatore-35096519-500-280.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115836\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/Damon-damon-salvatore-35096519-500-280.gif\" alt=\"its you\" \/><\/a><\/p>\n<p style=\"padding-left: 30px;\">5. Tu <strong>buena fortuna<\/strong><\/p>\n<p>\u00bfTienes un trabajo que te encanta y te pagan bien? \u00a1Excelente! \u00bfTe gusta tu cuerpo y trabajas para mantenerlo saludable? \u00a1Perfecto! \u00bfTe sientes feliz mientras los dem\u00e1s est\u00e1n enojados? Ni te preocupes, no debes de <strong>sentirte culpable<\/strong> al respecto. Haz trabajado duro por lo que quieres y tienes derecho de ser feliz. Si tu vida va de maravilla, si\u00e9ntete feliz al respecto porque lo mereces.<\/p>\n<p><a href=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/jane-dance.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115837\" src=\"http:\/\/mujerde10.com\/wp-content\/uploads\/2015\/12\/jane-dance.gif\" alt=\"jane-dance\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\">Tambi\u00e9n te puede interesar:<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/mujerde10.com\/2015\/10\/estar-bien\/salud\/felicidad-en-una-palabra-serotonina\">Felicidad en una palabra: SEROTONINA<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/mujerde10.com\/2015\/11\/recetas\/3-postres-veganos-con-chocolate-que-puedes-comer-sin-culpa\">3 Postres veganos con chocolate que puedes comer sin culpa<\/a><\/p>\n<p style=\"padding-left: 30px;\">\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres somos as\u00ed: llegamos a sentirnos culpables de todo lo que nos pasa, de lo que hacemos y hasta de lo que no hacemos. Pues esta [&hellip;]<\/p>\n","protected":false},"author":8248,"featured_media":116374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[16398,16397,791],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2015\/12\/jar-ir.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/115806"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/8248"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=115806"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/115806\/revisions"}],"predecessor-version":[{"id":115851,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/115806\/revisions\/115851"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/116374"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=115806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=115806"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=115806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}