{"id":124882,"date":"2016-02-04T08:00:57","date_gmt":"2016-02-04T14:00:57","guid":{"rendered":"http:\/\/mujerde10.com\/?p=124882"},"modified":"2016-02-03T08:36:07","modified_gmt":"2016-02-03T14:36:07","slug":"geminis-4-de-febrero-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/geminis\/geminis-4-de-febrero-2016\/2016\/02\/","title":{"rendered":"G\u00e9minis 4 de febrero 2016"},"content":{"rendered":"<p>Aspectos vertiginosos son los que vivir\u00e1s este d\u00eda, ya que se forman aspectos fuertes en tu zona de la trasmutaci\u00f3n y cosas ocultas, por lo que una verdad ya sea incomoda o no saldr\u00e1 a la luz este d\u00eda, no te afecta pero si cambia la perspectiva que ten\u00edas de algunas personas. En el plano del amor, tal vez tu no le des mucha importancia a la fechas, pero la persona que est\u00e1 a tu lado s\u00ed, por lo que es importante anotes y recuerdes esos d\u00edas importantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aspectos vertiginosos son los que vivir\u00e1s este d\u00eda, ya que se forman aspectos fuertes en tu zona de la trasmutaci\u00f3n y cosas ocultas, por lo que una [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":1395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[397,374],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2015\/03\/horoscopos-geminis.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/124882"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=124882"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/124882\/revisions"}],"predecessor-version":[{"id":124883,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/124882\/revisions\/124883"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/1395"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=124882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=124882"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=124882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}