{"id":145475,"date":"2016-06-16T08:00:27","date_gmt":"2016-06-16T13:00:27","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=145475"},"modified":"2016-06-16T09:00:32","modified_gmt":"2016-06-16T14:00:32","slug":"geminis-16-junio-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/geminis\/geminis-16-junio-2016\/2016\/06\/","title":{"rendered":"G\u00e9minis 16 de junio 2016"},"content":{"rendered":"<p>Tienes el apoyo de Sol, Venus y Mercurio en tu signo, as\u00ed que esta quincena aprovecha y paga tus deudas. En el plano del amor, que dif\u00edcil es para tu pareja proponerte planes nuevos, pero la vida siempre evoluciona, as\u00ed que esc\u00fachale, ya que el final quien se beneficia ser\u00e1s t\u00fa. Cierra de una vez ciclos del pasado, hay situaciones que no volver\u00e1n a ser como antes y debes de aceptarlo. Ya no busques el amor, te llega antes de lo que imaginas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tienes el apoyo de Sol, Venus y Mercurio en tu signo, as\u00ed que esta quincena aprovecha y paga tus deudas. En el plano del amor, que dif\u00edcil [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":1395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[397],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2015\/03\/horoscopos-geminis.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/145475"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=145475"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/145475\/revisions"}],"predecessor-version":[{"id":145476,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/145475\/revisions\/145476"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/1395"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=145475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=145475"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=145475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}