{"id":146781,"date":"2016-06-24T08:00:09","date_gmt":"2016-06-24T13:00:09","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=146781"},"modified":"2016-06-24T16:20:39","modified_gmt":"2016-06-24T21:20:39","slug":"tauro-24-junio-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/tauro\/tauro-24-junio-2016\/2016\/06\/","title":{"rendered":"Tauro 24 de junio 2016"},"content":{"rendered":"<p>Toma en cuenta que las cosas no ser\u00e1n tan dif\u00edciles como aparenten serlo, as\u00ed que a cualquier complicaci\u00f3n que aparezca, mant\u00e9n la calma y sobre todo la mente fr\u00eda, la objetividad ser\u00e1 tu mejor amiga en estos d\u00edas. En el plano de la pareja todo debe ir bien. Si est\u00e1s saliendo con alguien, date un poco a desear. En el plano del dinero hay buenas sorpresas. Se arreglan las diferencias con alg\u00fan familiar. En el trabajo vas por el buen camino, no dejes de so\u00f1ar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toma en cuenta que las cosas no ser\u00e1n tan dif\u00edciles como aparenten serlo, as\u00ed que a cualquier complicaci\u00f3n que aparezca, mant\u00e9n la calma y sobre todo la [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":146620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[308],"tags":[389],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2016\/06\/tauro-hor\u00f3scopos.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/146781"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=146781"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/146781\/revisions"}],"predecessor-version":[{"id":146782,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/146781\/revisions\/146782"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/146620"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=146781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=146781"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=146781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}