{"id":147025,"date":"2016-06-25T08:00:14","date_gmt":"2016-06-25T13:00:14","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=147025"},"modified":"2016-06-25T12:18:25","modified_gmt":"2016-06-25T17:18:25","slug":"acuario-25-junio-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/acuario\/acuario-25-junio-2016\/2016\/06\/","title":{"rendered":"Acuario 25 de junio 2016"},"content":{"rendered":"<p>Hoy se pueden presentar algunas adversidades u obst\u00e1culos que te hagan creer que no vas por el buen camino, pero solo es una prueba del universo, no tienes que hacer nada m\u00e1s que mantenerte en el camino que llevas. Urano y J\u00fapiter trabajan juntos en tu zona de las finanzas, lo cual puede provocar que por quedar bien con alguien o por tratar de arreglar t\u00fa situaci\u00f3n de pareja, puedes hacer un gasto innecesario que te provoque un gran desajuste en las pr\u00f3ximas semanas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy se pueden presentar algunas adversidades u obst\u00e1culos que te hagan creer que no vas por el buen camino, pero solo es una prueba del universo, no [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":146784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[317],"tags":[422],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2016\/06\/acuario-hor\u00f3scopos.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/147025"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=147025"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/147025\/revisions"}],"predecessor-version":[{"id":147027,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/147025\/revisions\/147027"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/146784"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=147025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=147025"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=147025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}