{"id":166159,"date":"2016-10-14T08:00:43","date_gmt":"2016-10-14T13:00:43","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=166159"},"modified":"2016-10-14T09:11:55","modified_gmt":"2016-10-14T14:11:55","slug":"libra-14-octubre-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/libra\/libra-14-octubre-2016\/2016\/10\/","title":{"rendered":"Libra 14 de octubre 2016"},"content":{"rendered":"<p>En algunas ocasiones hay que dar situaciones en perdida, y el d\u00eda de hoy tendr\u00e1s que hacerlo, deber\u00e1s reconocer que algo se sali\u00f3 de control y al final no se obtendr\u00e1n resultados positivos y que es mejor evitar m\u00e1s complicaciones, aunque es un aprendizaje m\u00e1s. En el plano del amor, no es posible que siempre te lleves la mejor parte, recuerda que una pareja es significado \u00a0de equidad. Las finanzas arrancan su carrera final, aprovecha este ciclo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En algunas ocasiones hay que dar situaciones en perdida, y el d\u00eda de hoy tendr\u00e1s que hacerlo, deber\u00e1s reconocer que algo se sali\u00f3 de control y al [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":146788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[313],"tags":[418],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2016\/06\/libra-hor\u00f3scopos.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166159"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=166159"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166159\/revisions"}],"predecessor-version":[{"id":166160,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166159\/revisions\/166160"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/146788"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=166159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=166159"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=166159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}