{"id":166517,"date":"2016-10-19T09:09:18","date_gmt":"2016-10-19T14:09:18","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=166517"},"modified":"2016-10-19T09:09:18","modified_gmt":"2016-10-19T14:09:18","slug":"tauro-19-octubre-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/tauro\/tauro-19-octubre-2016\/2016\/10\/","title":{"rendered":"Tauro 19 de octubre 2016"},"content":{"rendered":"<p>Algunas situaciones laborales o de la vida cotidiana podr\u00edan no salir como imaginas, pero eso no significa que tengan un mal resultado, por lo que se recomienda persistir y esperar un poco, si quieres resultados efectivos y positivos en lo que est\u00e1s haciendo, evita conectarte con la negatividad o pesimismo de las noticias moment\u00e1neas. En el plano del amor es necesario brindarte el tiempo para cumplir ese compromiso o promesa junto a tu pareja. Mejora la econom\u00eda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunas situaciones laborales o de la vida cotidiana podr\u00edan no salir como imaginas, pero eso no significa que tengan un mal resultado, por lo que se recomienda [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":146620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[308],"tags":[374,389],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2016\/06\/tauro-hor\u00f3scopos.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166517"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=166517"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166517\/revisions"}],"predecessor-version":[{"id":166518,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166517\/revisions\/166518"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/146620"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=166517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=166517"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=166517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}