{"id":166519,"date":"2016-10-19T09:10:25","date_gmt":"2016-10-19T14:10:25","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=166519"},"modified":"2016-10-19T09:10:25","modified_gmt":"2016-10-19T14:10:25","slug":"geminis-19-octubre-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/geminis\/geminis-19-octubre-2016\/2016\/10\/","title":{"rendered":"G\u00e9minis 19 de octubre 2016"},"content":{"rendered":"<p>Debido a algunas decisiones que tomaste por impulso las consecuencias u obst\u00e1culos con los que tendr\u00e1s que experimentar en este d\u00eda son lecciones, as\u00ed que mejor no discutas y acepta las recomendaciones para sacar los proyectos con \u00e9xito en y es mejor que esperes un poco para aceptar nuevas tareas. Tu humor no ser\u00e1 el mejor, evita las situaciones que te provoquen alguna molestia y as\u00ed evitaras conflictos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a algunas decisiones que tomaste por impulso las consecuencias u obst\u00e1culos con los que tendr\u00e1s que experimentar en este d\u00eda son lecciones, as\u00ed que mejor no [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":146623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[397,374],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2016\/06\/geminis-hor\u00f3scopos.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166519"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=166519"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166519\/revisions"}],"predecessor-version":[{"id":166520,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166519\/revisions\/166520"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/146623"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=166519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=166519"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=166519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}