{"id":166523,"date":"2016-10-19T09:12:14","date_gmt":"2016-10-19T14:12:14","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=166523"},"modified":"2016-10-19T09:12:14","modified_gmt":"2016-10-19T14:12:14","slug":"leo-19-octubre-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/leo\/leo-19-octubre-2016\/2016\/10\/","title":{"rendered":"Leo 19 de octubre 2016"},"content":{"rendered":"<p>Esta vez el mensaje del cosmos es claro, debes aprender a ser m\u00e1s concreto en tus planes, metas y deseos, estas dejando al aire la estructura que te puede llevar al \u00e9xito, analiza las cosas m\u00e1s de dos veces para que los detalles sean tu herramienta de vida en estos d\u00edas. En el aspecto econ\u00f3mico tus finanzas estar\u00e1n m\u00e1s sanas y fuertes, pero ayuda en este tema, ya que tu buen coraz\u00f3n no pone l\u00edmites a la hora de ayudar, tu sabes quienes si est\u00e1n de tu lado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta vez el mensaje del cosmos es claro, debes aprender a ser m\u00e1s concreto en tus planes, metas y deseos, estas dejando al aire la estructura que [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":146787,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[374,405],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2016\/06\/leo-hor\u00f3scopos.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166523"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=166523"}],"version-history":[{"count":1,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166523\/revisions"}],"predecessor-version":[{"id":166524,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166523\/revisions\/166524"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/146787"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=166523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=166523"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=166523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}