{"id":166718,"date":"2016-10-20T08:00:13","date_gmt":"2016-10-20T13:00:13","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=166718"},"modified":"2016-10-20T08:47:06","modified_gmt":"2016-10-20T13:47:06","slug":"tauro-20-octubre-2016","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/horoscopos\/tauro\/tauro-20-octubre-2016\/2016\/10\/","title":{"rendered":"Tauro 20 de octubre 2016"},"content":{"rendered":"<p>Est\u00e1s aprendiendo lecciones importantes de superaci\u00f3n, es probable tengas que apoyar a alguien que estimes, no lo dudes. Vivir\u00e1s una etapa en la que debes poner a trabajar tu ingenio, para poder tener \u00e9xito en las nuevas tareas u obligaciones que estar\u00e1n llegando a t\u00fa vida, al final de todo esto, veras la recompensa, tanto en dinero como en conocimiento. El amor, te sonr\u00ede y ahora si no habr\u00e1 pretextos para que puedas conquistar de una vez por todas a esa persona que te gusta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1s aprendiendo lecciones importantes de superaci\u00f3n, es probable tengas que apoyar a alguien que estimes, no lo dudes. Vivir\u00e1s una etapa en la que debes poner a [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":146620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[308],"tags":[389],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2016\/06\/tauro-hor\u00f3scopos.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166718"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=166718"}],"version-history":[{"count":2,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166718\/revisions"}],"predecessor-version":[{"id":166720,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/166718\/revisions\/166720"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/146620"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=166718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=166718"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=166718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}