{"id":181053,"date":"2017-04-04T20:00:20","date_gmt":"2017-04-05T01:00:20","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=181053"},"modified":"2017-04-04T18:33:14","modified_gmt":"2017-04-04T23:33:14","slug":"como-evitar-mosquitos-en-tu-casa-en-epoca-de-calor","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/mujeres-al-rescate\/como-evitar-mosquitos-en-tu-casa-en-epoca-de-calor\/2017\/04\/","title":{"rendered":"C\u00f3mo evitar mosquitos en tu casa en \u00e9poca de calor"},"content":{"rendered":"<p>El calor es el mejor amigo de los mosquitos. Seguro ya lo notaste por las noches, cuando no te dejan dormir con su zumbido. Y si tienes patio o jard\u00edn, \u00a1olv\u00eddate de relajarte ah\u00ed, porque te comen viva! Pero no te preocupes, porque investigu\u00e9\u00a0<strong>c\u00f3mo evitar mosquitos en tu casa en \u00e9poca de calor<\/strong>. Esto es lo que puedes hacer&#8230;<\/p>\n<p>Lo primero que debes hacer es <strong>evitar tener botes o recipientes con agua<\/strong>\u00a0estancada en alguna zona de tu casa, tanto dentro como fuera, porque es donde se reproducen naturalmente. As\u00ed que revisa bien y elimina cualquier charquito o fuente de agua, sobre todo en exteriores. eso incluye floreros, agua de bebederos de mascotas, charcos en lavaderos&#8230; \u00a1todo!<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-181054\" src=\"http:\/\/www.mujerde10.com\/wp-content\/uploads\/2017\/04\/evitar-mosquitos-casa-epoca-calor4.jpg\" alt=\"evitar mosquitos casa epoca calor2\" \/><\/p>\n<p class=\"selectionShareable\">Otra opci\u00f3n muy l\u00f3gica pero que muchas veces olvidamos es <strong>cerrar las ventanas y puertas para que no entren.<\/strong> Ya s\u00e9, el calor est\u00e1 imposible y pocos tenemos aire acondicionado. Pero si quieres evitar su dulce zumbido, tendr\u00e1s que cerrar todo a piedra y lodo. No hay m\u00e1s. Tambi\u00e9n ten cuidado con las rendijas porque entran hasta por el m\u00e1s m\u00ednimo huequito, buscando un lugar calientito.<\/p>\n<p class=\"selectionShareable\">Para reforzar, puedes encender -tanto en interiores como en exteriores- <strong>una vela de citronela<\/strong>. Esta planta parecida al pasto desprende un olor que los espanta, as\u00ed que es muy efectiva. Los \u00a0repelentes para moscos tambi\u00e9n son efectivos, pero la citronela es m\u00e1s natural y menos t\u00f3xica.<\/p>\n<div id=\"attachment_181056\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-181056\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-181056\" src=\"http:\/\/www.mujerde10.com\/wp-content\/uploads\/2017\/04\/evitar-mosquitos-casa-epoca-calor2.jpg\" alt=\"evitar mosquitos casa epoca calor2\" \/><p id=\"caption-attachment-181056\" class=\"wp-caption-text\">As\u00ed luce una planta de citronela.<\/p><\/div>\n<p class=\"selectionShareable\">Si de plano sabes que tendr\u00e1s plaga, <strong>manda a fumigar con un profesional.<\/strong><\/p>\n<p class=\"selectionShareable\">Tambi\u00e9n, dicen los expertos, es preferible <strong>cambiar los focos muy blancos y brillantes por otros m\u00e1s tenues<\/strong> o de luz amarilla, porque la iluminaci\u00f3n fuerte los atrae much\u00edsimo. Adem\u00e1s, los LED atraen menos moscos que los incandescentes.<\/p>\n<p class=\"selectionShareable\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-181055\" src=\"http:\/\/www.mujerde10.com\/wp-content\/uploads\/2017\/04\/evitar-mosquitos-casa-epoca-calor23.jpg\" alt=\"evitar mosquitos casa epoca calor2\" \/><\/p>\n<p class=\"selectionShareable\">Si vives en climas c\u00e1lidos, seguramente ya tienes <strong>mosquiteros<\/strong> en puertas y ventanas. Nada m\u00e1s revisa bien que no tengan hoyos y que est\u00e9n en perfecto estado. Tambi\u00e9n puedes ponerlos alrededor de tu cama, por supuesto. \u00a1Son un paro!<\/p>\n<p class=\"selectionShareable\">Como dato curioso, los mosquitos atacan, m\u00e1s en la ma\u00f1ana y al atardecer o en la noche, no tanto durante el d\u00eda, as\u00ed que tenlo en cuenta si vas a tener una cenita al aire libre o si sales a correr.<\/p>\n<p class=\"selectionShareable\"><strong>Sigue estos tips para evitar mosquitos en tu casa en \u00e9poca de calor. Recuerda que pueden transmitir enfermedades y ojo, nadie estamos exentos de contraerlas.<\/strong><\/p>\n<p><iframe loading=\"lazy\" class=\"giphy-embed\" src=\"\/\/giphy.com\/embed\/yPbYgQZT8UlLG\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p class=\"selectionShareable\"><strong>Si quieres saber c\u00f3mo utilizar correctamente la citronela, mira:<\/strong><\/p>\n<blockquote data-secret=\"EC3PBu13lC\" class=\"wp-embedded-content\"><p><a href=\"http:\/\/www.mujerde10.com\/2016\/07\/mujeres-al-rescate\/fuera-moscos-con-citronela\/\">Fuera moscos con citronela<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"http:\/\/www.mujerde10.com\/2016\/07\/mujeres-al-rescate\/fuera-moscos-con-citronela\/embed\/#?secret=EC3PBu13lC\" data-secret=\"EC3PBu13lC\" title=\"&#8220;Fuera moscos con citronela&#8221; &#8212; Mujer de 10\" frameborder=\"0\" marginmarginscrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nada m\u00e1s llega el calor \u00a1y con \u00e9l aparecen los mosquitos! Jaja, \u00bfa poco no? Adem\u00e1s de molestos, pueden traer enfermedades como dengue, zika y chikungunya. Por eso, te digo c\u00f3mo evitar mosquitos en tu casa en \u00e9poca de calor. Aplica estos tips.<\/p>\n","protected":false},"author":4,"featured_media":181058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20339,22902],"tags":[23389,23385,23387,23386,23388],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2017\/04\/evitar-mosquitos-casa-epoca-calor.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/181053"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=181053"}],"version-history":[{"count":2,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/181053\/revisions"}],"predecessor-version":[{"id":181060,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/181053\/revisions\/181060"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/181058"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=181053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=181053"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=181053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}