{"id":181905,"date":"2017-04-13T15:00:23","date_gmt":"2017-04-13T20:00:23","guid":{"rendered":"http:\/\/www.mujerde10.com\/?p=181905"},"modified":"2017-04-12T20:16:31","modified_gmt":"2017-04-13T01:16:31","slug":"cosas-debes-saber-si-tu-vuelo-esta-sobrevendido","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/mujeres-al-rescate\/cosas-debes-saber-si-tu-vuelo-esta-sobrevendido\/2017\/04\/","title":{"rendered":"\u00bfQu\u00e9 puedo hacer si mi vuelo est\u00e1 sobrevendido?"},"content":{"rendered":"<p>No te alarmes no es el fin de tus vacaciones, de hecho, el <i>overbooking<\/i> es una pr\u00e1ctica habitual y legal en muchas aerol\u00edneas que venden hasta 5% m\u00e1s de las plazas de las que disponen, por los pasajeros que no se presentan a abordar el d\u00eda del vuelo.<\/p>\n<p>Una de las cosas que debes saber es que est\u00e1 practica est\u00e1 regulada y que la Ley te respalda pero lamento decirte que si llegaste tarde o simplemente ya est\u00e1 todo ocupado al momento de abordar, s\u00f3lo tienes dos opciones: Ser voluntario en un vuelo sobrevendido\u00a0o ponerte de u\u00f1as\u00a0y exigir el lugar que ya pagaste. <strong>S\u00f3lo esperamos que no te saquen a patadas.<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-181907\" src=\"http:\/\/www.mujerde10.com\/wp-content\/uploads\/2017\/04\/avion-300x188.jpg\" alt=\"\u00bfQu\u00e9 puedo hacer si mi vuelo est\u00e1 sobrevendido? 0\" \/><\/p>\n<p><b>Voluntarios\u00a0para vuelo sobrevendido<\/b><\/p>\n<p>Existen voluntarios <em>overbooking<\/em> \u00a1Aunque no lo creas! Son personas que renuncian pac\u00edficamente a su lugar en el avi\u00f3n y a cambio reciben beneficios adicionales por su &#8216;valiosa cooperaci\u00f3n&#8217;.\u00a0Probablemente\u00a0te pedir\u00e1n &#8216;amablemente&#8217; abandonar el vuelo y abordar en el pr\u00f3ximo m\u00e1s cercano pero <strong>\u00bfQu\u00e9 puedes negociar?<\/strong><\/p>\n<ul>\n<li><strong>La devoluci\u00f3n de tu dinero en un lapso no mayor a 7 d\u00edas,<\/strong> adem\u00e1s de un vuelo de vuelta al primer punto de partida lo m\u00e1s r\u00e1pidamente posible (S\u00f3lo si procede).<\/li>\n<li><strong>Si est\u00e1s haciendo un tour<\/strong> y el vuelo est\u00e1\u00a0sobrevendido<em>,<\/em>\u00a0podr\u00e1s <strong>pedir a la aerol\u00ednea la devoluci\u00f3n integra del pago inicial<\/strong> (menos los viajes ya realizados), siempre y cuando el vuelo ya no tenga\u00a0sentido respecto al plan de viaje inicial, adem\u00e1s tendr\u00e1s derecho a un vuelo de regreso\u00a0al primer punto de partida lo m\u00e1s r\u00e1pido\u00a0posible.<\/li>\n<li><strong>Traslado a tu destino por medios de transporte comparables<\/strong>.\u00a0Adem\u00e1s, tienes la posibilidad de negociar <strong>beneficios adicionales<\/strong> como cheques de viajes, dinero en met\u00e1lico o asiento en primera clase.<\/li>\n<li>Un boleto\u00a0para volar al mismo destino pero<strong> en otra fecha<\/strong>. En ocasiones te pedir\u00e1n viajar un d\u00eda despu\u00e9s, en estos casos la aerol\u00ednea tendr\u00e1 que cubrir los gastos de traslado. \u00a0De lo malo, lo recuperado. \u00bfNo?<\/li>\n<\/ul>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-181908\" src=\"http:\/\/www.mujerde10.com\/wp-content\/uploads\/2017\/04\/avion2-300x200.jpg\" alt=\"\u00bfQu\u00e9 puedo hacer si mi vuelo est\u00e1 sobrevendido? 1\" \/><\/p>\n<p><strong>Personas contra el <em>overbooking<\/em><\/strong><\/p>\n<p>Lo que menos queremos es perder tiempo por este tipo de situaciones\u00a0ajenas a nosotros, as\u00ed que <strong>si tu vuelo esta sobrevendido<\/strong>, no te permiten el acceso y <strong>no quieres ser un voluntario<\/strong>, esto es lo que debes hacer. <strong>Aunque te aviso\u00a0que no podr\u00e1s llegar a tiempo.<\/strong><\/p>\n<ul class=\"list\">\n<li>Lo primordial es <strong>mostrar tu desacuerdo<\/strong>\u00a0<strong>mediante un escrito<\/strong> que narre lo sucedido, deber\u00e1 estar fechada. Para ello puedes acercarte al mostrador de tu compa\u00f1\u00eda o en su defecto a las autoridades\u00a0para <strong>pedir un documento que acredite el <em>overbooking<\/em>.<\/strong><\/li>\n<li>Puedes pedir el <strong>derecho de asistencia<\/strong> en el cual la\u00a0compa\u00f1\u00eda se hace cargo de los gastos generados en caso de\u00a0que la salida del transporte alternativo se producta al d\u00eda siguiente o d\u00edas m\u00e1s tarde.<\/li>\n<li>A <strong>pedir una indemnizaci\u00f3n<\/strong> por las molestias generadas por el inconveniente.<\/li>\n<\/ul>\n<p>En caso de sobrecupo, la aerol\u00ednea puede\u00a0negar el acceso de pasajeros pero <strong>en ning\u00fan momento\u00a0tiene derecho a desalojarlos.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1s s\u00faper entusiasmada por tu pr\u00f3ximo viaje, haces mil horas preparando tu maleta, subes al taxi para ir al aeropuerto y cuando llegas&#8230; \u00a1Sorpresa! Tu vuelo est\u00e1 sobrevendido.<\/p>\n","protected":false},"author":4,"featured_media":181906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20339],"tags":[368,23493],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2017\/04\/overbookin.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/181905"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=181905"}],"version-history":[{"count":2,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/181905\/revisions"}],"predecessor-version":[{"id":181911,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/181905\/revisions\/181911"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/181906"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=181905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=181905"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=181905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}