{"id":99258,"date":"2015-08-18T08:00:00","date_gmt":"2015-08-18T13:00:00","guid":{"rendered":"http:\/\/mujerde10.com\/?p=99258"},"modified":"2015-08-17T20:55:02","modified_gmt":"2015-08-18T01:55:02","slug":"10-tipos-de-cancer-mas-frecuentes-en-mujeres-y-sus-sintomas","status":"publish","type":"post","link":"http:\/\/desarrollo.grupomedios.com\/mujer\/bienestar\/10-tipos-de-cancer-mas-frecuentes-en-mujeres-y-sus-sintomas\/2015\/08\/","title":{"rendered":"10 tipos de c\u00e1ncer m\u00e1s frecuentes en mujeres y sus s\u00edntomas"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: center;\"><em>Las mujeres somos suceptibles de padecer espec\u00edficamente estos tipos de c\u00e1ncer. \u00a1Con\u00f3celos!<br \/>\n<\/em><\/p>\n<\/blockquote>\n<p>Conoce estos 10 tipos de c\u00e1ncer m\u00e1s frecuentes en mujeres y sus s\u00edntomas:<\/p>\n<p><img decoding=\"async\" class=\"alwaysThinglink\" style=\"max-width: 100%;\" src=\"\/\/cdn.thinglink.me\/api\/image\/690004751810560000\/1024\/10\/scaletowidth#tl-690004751810560000;1043138249'\" alt=\"10 tipos de c\u00e1ncer m\u00e1s frecuentes en mujeres y sus s\u00edntomas 0\" \/><script src=\"\/\/cdn.thinglink.me\/jse\/embed.js\" async=\"\" charset=\"utf-8\"><\/script><script src=\"\/\/cdn.thinglink.me\/jse\/embed.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p>Si bien un s\u00edntoma puede tener m\u00faltiples causas, una de ellas puede ser el c\u00e1ncer. Siempre pregunta a tu m\u00e9dico, no te quedes con la duda si notas alg\u00fan cambio en tu cuerpo.<\/p>\n<p>El c\u00e1ncer es curable si se detecta a tiempo, y lo m\u00e1s importante es saber que podemos prevenirlo:<\/p>\n<p><a href=\"http:\/\/mujerde10.com\/fernanda\/aguas-con-los-tintes-podrian-ocasionar-cancer\/\" target=\"_blank\">\u00a1Aguas con los tintes! Podr\u00edan ocasionar c\u00e1ncer<\/a><\/p>\n<p><a href=\"http:\/\/mujerde10.com\/2015\/07\/estar-bien\/salud\/6-tips-para-prevenir-el-cancer-de-piel\/\" target=\"_blank\">6 tips para prevenir el c\u00e1ncer de piel<\/a><\/p>\n<p><a href=\"http:\/\/mujerde10.com\/fernanda\/cosas-que-no-sabias-sobre-el-cancer-de-mama\/\" target=\"_blank\">Cosas que NO sab\u00edas sobre el c\u00e1ncer de mama<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres somos suceptibles de padecer espec\u00edficamente estos tipos de c\u00e1ncer. \u00a1Con\u00f3celos! Conoce estos 10 tipos de c\u00e1ncer m\u00e1s frecuentes en mujeres y sus s\u00edntomas: Si bien [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":99268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[398,10889,14763],"fimg_url":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-content\/uploads\/2015\/08\/reiki-tratamiento-cc3a1ncer-mama.jpg","amp_enabled":true,"_links":{"self":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/99258"}],"collection":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/comments?post=99258"}],"version-history":[{"count":3,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/99258\/revisions"}],"predecessor-version":[{"id":99271,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/posts\/99258\/revisions\/99271"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media\/99268"}],"wp:attachment":[{"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/media?parent=99258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/categories?post=99258"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/desarrollo.grupomedios.com\/mujer\/wp-json\/wp\/v2\/tags?post=99258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}